{"id":114,"date":"2014-09-18T17:37:19","date_gmt":"2014-09-18T17:37:19","guid":{"rendered":"http:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec.png"},"modified":"2014-09-18T17:37:19","modified_gmt":"2014-09-18T17:37:19","slug":"aulasec","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/zerventsere\/aulasec\/","title":{"rendered":"aulasec"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"class_list":["post-114","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"87\" src=\"https:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec-300x87.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec-300x87.png 300w, https:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec-1024x299.png 1024w, https:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec.png 1124w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href='https:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec.png'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1124,"height":329,"file":"2014\/09\/aulasec.png","sizes":{"thumbnail":{"file":"aulasec-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec-150x150.png"},"medium":{"file":"aulasec-300x87.png","width":300,"height":87,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec-300x87.png"},"large":{"file":"aulasec-1024x299.png","width":1024,"height":299,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec-1024x299.png"},"thumb-300":{"file":"aulasec-300x250.png","width":300,"height":250,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec-300x250.png"},"thumb-200":{"file":"aulasec-200x150.png","width":200,"height":150,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec-200x150.png"},"full":{"file":"aulasec.png","width":1124,"height":329,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":null,"source_url":"https:\/\/agora.xtec.cat\/zerventsere\/wp-content\/uploads\/usu867\/2014\/09\/aulasec.png","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/zerventsere\/wp-json\/wp\/v2\/media\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/zerventsere\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/zerventsere\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/zerventsere\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/zerventsere\/wp-json\/wp\/v2\/comments?post=114"}]}}