{"id":6646,"date":"2026-06-15T15:50:10","date_gmt":"2026-06-15T13:50:10","guid":{"rendered":"https:\/\/agora.xtec.cat\/zerventdavall\/?p=6646"},"modified":"2026-06-15T15:50:10","modified_gmt":"2026-06-15T13:50:10","slug":"festa-comiat-de-lalumnat-de-6e","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/zerventdavall\/general\/festa-comiat-de-lalumnat-de-6e\/","title":{"rendered":"Festa Comiat de l&#8217;alumnat de 6\u00e8"},"content":{"rendered":"<p>Avui 15 de juny\u00a0 tot l\u2019alumnat de 6\u00e8 de la ZER ens hem trobat a l\u2019escola Mare de D\u00e9u del Portal a Els Prats de Rei per acomiadar el curs i l\u2019etapa educativa.<\/p>\n<p>En Consell de Direcci\u00f3 de la ZER es va decidir de fer aquesta trobada ja que no es va poder dur a terme la Festa de la ZER.<\/p>\n<p>Hem fet un joc de coneixen\u00e7a, un Kahoot amb preguntes sobre la ZER (amb detalls per a tots els participants), improvisaci\u00f3 per grups i s\u2019ha cantat l\u2019Himne de la ZER.<\/p>\n<p>La ZER ha obsequiat l\u2019alumnat amb esmorzar i la samarreta de la ZER.<\/p>\n<p>Ha estat un mat\u00ed de germanor amb molt bon ambient.<\/p>\n<p>&nbsp;<\/p>\n<p>Aqu\u00ed podeu veure les fotos:<\/p>\n<p><a href=\"https:\/\/photos.app.goo.gl\/2YRkGCPvfmq6uh5SA\">https:\/\/photos.app.goo.gl\/2YRkGCPvfmq6uh5SA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avui 15 de juny\u00a0 tot l\u2019alumnat de 6\u00e8 de la ZER ens hem trobat a l\u2019escola Mare de D\u00e9u del Portal a Els Prats de Rei per acomiadar el curs i l\u2019etapa educativa.<br \/>\nEn Consell de Direcci\u00f3 de la ZER es va decidir de fer aquesta&hellip;  <a href=\"https:\/\/agora.xtec.cat\/zerventdavall\/general\/festa-comiat-de-lalumnat-de-6e\/\" title=\"Read Festa Comiat de l&#8217;alumnat de 6\u00e8\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":6647,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[163,119,1,118],"tags":[],"class_list":["post-6646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curs-25-26","category-festeszer","category-general","category-zer"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/zerventdavall\/wp-json\/wp\/v2\/posts\/6646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/zerventdavall\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/zerventdavall\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/zerventdavall\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/zerventdavall\/wp-json\/wp\/v2\/comments?post=6646"}],"version-history":[{"count":1,"href":"https:\/\/agora.xtec.cat\/zerventdavall\/wp-json\/wp\/v2\/posts\/6646\/revisions"}],"predecessor-version":[{"id":6648,"href":"https:\/\/agora.xtec.cat\/zerventdavall\/wp-json\/wp\/v2\/posts\/6646\/revisions\/6648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/zerventdavall\/wp-json\/wp\/v2\/media\/6647"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/zerventdavall\/wp-json\/wp\/v2\/media?parent=6646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/zerventdavall\/wp-json\/wp\/v2\/categories?post=6646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/zerventdavall\/wp-json\/wp\/v2\/tags?post=6646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}