{"id":14326,"date":"2022-05-27T11:25:49","date_gmt":"2022-05-27T09:25:49","guid":{"rendered":"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/?p=14326"},"modified":"2022-05-29T18:38:40","modified_gmt":"2022-05-29T16:38:40","slug":"fotografia-al-a-girona-temps-de-flors-4t-deso","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/portada\/fotografia-al-a-girona-temps-de-flors-4t-deso\/","title":{"rendered":"GIRONA, TEMPS DE FLORS (RUTA FOTOGR\u00c0FICA). 4t D&#8217;ESO"},"content":{"rendered":"<p>El passat divendres 13 de maig, l\u2019alumnat de 4t d\u2019ESO de l&#8217;optativa d\u2019Educaci\u00f3 Visual i Pl\u00e0stica va visitar el Barri Vell per fer una ruta fotogr\u00e0fica aprofitant l\u2019esdeveniment \u201cGirona, temps de flors\u201d.<\/p>\n<p>L\u2019activitat va servir per treballar diferents aspectes de composici\u00f3 i enfocament en fotografia.<\/p>\n<p>Aqu\u00ed teniu alguns exemples dels nostres artistes:<\/p>\n\r\n\t<div class=\"slideshow_container slideshow_container_style-light\" style=\"height: 600px; \" data-slideshow-id=\"14343\" data-style-name=\"style-light\" data-style-version=\"2.3.1\" >\r\n\r\n\t\t\t\t\t<div class=\"slideshow_loading_icon\"><\/div>\r\n\t\t\r\n\t\t<div class=\"slideshow_content\" style=\"display: none;\">\r\n\r\n\t\t\t<div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-content\/uploads\/usu1009\/2022\/05\/IMG_20220513_112546.jpg\" alt=\"IMG_20220513_112546\" width=\"1080\" height=\"1440\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_20220513_112546<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-content\/uploads\/usu1009\/2022\/05\/IMG_20220513_111832.jpg\" alt=\"IMG_20220513_111832\" width=\"1080\" height=\"1440\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_20220513_111832<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-content\/uploads\/usu1009\/2022\/05\/1653038030177.jpg\" alt=\"1653038030177\" width=\"1671\" height=\"1085\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">1653038030177<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-content\/uploads\/usu1009\/2022\/05\/20220513_113619-scaled.jpg\" alt=\"20220513_113619\" width=\"2560\" height=\"1920\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">20220513_113619<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-content\/uploads\/usu1009\/2022\/05\/C0F1E31C-4AEF-4C77-A42B-8B758CBC612D.jpeg\" alt=\"C0F1E31C-4AEF-4C77-A42B-8B758CBC612D\" width=\"1469\" height=\"1959\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">C0F1E31C-4AEF-4C77-A42B-8B758CBC612D<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-content\/uploads\/usu1009\/2022\/05\/IMG_20220520_182504_717.jpg\" alt=\"IMG_20220520_182504_717\" width=\"320\" height=\"711\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_20220520_182504_717<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-content\/uploads\/usu1009\/2022\/05\/IMG_20220520_182457_020.jpg\" alt=\"IMG_20220520_182457_020\" width=\"320\" height=\"711\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_20220520_182457_020<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-content\/uploads\/usu1009\/2022\/05\/1653038030386.jpg\" alt=\"1653038030386\" width=\"1200\" height=\"1600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">1653038030386<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-content\/uploads\/usu1009\/2022\/05\/1653038030315.jpg\" alt=\"1653038030315\" width=\"1200\" height=\"1600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">1653038030315<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-content\/uploads\/usu1009\/2022\/05\/20220513_105819-rotated-e1653643477230.jpg\" alt=\"20220513_105819\" width=\"1872\" height=\"2496\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">20220513_105819<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-content\/uploads\/usu1009\/2022\/05\/1653038030149.jpg\" alt=\"1653038030149\" width=\"1075\" height=\"1600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">1653038030149<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"slideshow_controlPanel slideshow_transparent\" style=\"display: none;\"><ul><li class=\"slideshow_togglePlay\" data-play-text=\"Visualitza\" data-pause-text=\"Pausa\"><\/li><\/ul><\/div>\r\n\r\n\t\t<div class=\"slideshow_button slideshow_previous slideshow_transparent\" role=\"button\" data-previous-text=\"Anterior\" style=\"display: none;\"><\/div>\r\n\t\t<div class=\"slideshow_button slideshow_next slideshow_transparent\" role=\"button\" data-next-text=\"Seg\u00fcent\" style=\"display: none;\"><\/div>\r\n\r\n\t\t<div class=\"slideshow_pagination\" style=\"display: none;\" data-go-to-text=\"V\u00e9s a la diapositiva\"><div class=\"slideshow_pagination_center\"><\/div><\/div>\r\n\r\n\t\t<!-- WordPress Slideshow Version 2.3.1 -->\r\n\r\n\t\t\t<\/div>\r\n\r\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El passat divendres 13 de maig, l\u2019alumnat de 4t d\u2019ESO de l&#8217;optativa d\u2019Educaci\u00f3 Visual i Pl\u00e0stica va visitar el Barri Vell per fer una ruta fotogr\u00e0fica aprofitant l\u2019esdeveniment \u201cGirona, temps de flors\u201d. L\u2019activitat va servir per treballar diferents aspectes de composici\u00f3 i enfocament en fotografia. Aqu\u00ed teniu alguns exemples dels nostres artistes: &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":14345,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[29],"tags":[],"class_list":["post-14326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-json\/wp\/v2\/posts\/14326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-json\/wp\/v2\/comments?post=14326"}],"version-history":[{"count":4,"href":"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-json\/wp\/v2\/posts\/14326\/revisions"}],"predecessor-version":[{"id":14330,"href":"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-json\/wp\/v2\/posts\/14326\/revisions\/14330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-json\/wp\/v2\/media\/14345"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-json\/wp\/v2\/media?parent=14326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-json\/wp\/v2\/categories?post=14326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/inssalvadorsunyer\/wp-json\/wp\/v2\/tags?post=14326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}