{"id":10419,"date":"2024-03-19T19:26:01","date_gmt":"2024-03-19T18:26:01","guid":{"rendered":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner.jpg"},"modified":"2024-03-19T19:26:01","modified_gmt":"2024-03-19T18:26:01","slug":"ajuts-post-baner","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/inselstresturons\/ajuts-post-baner\/","title":{"rendered":"Ajuts post b\u00e0ner"},"author":1,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"class_list":["post-10419","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"56\" src=\"https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner-300x56.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner-300x56.jpg 300w, https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner-1024x192.jpg 1024w, https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner-768x144.jpg 768w, https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner-1536x288.jpg 1536w, https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner.jpg 1890w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href='https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner.jpg'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1890,"height":354,"file":"2024\/03\/Ajuts-post-baner.jpg","filesize":75042,"sizes":{"medium":{"file":"Ajuts-post-baner-300x56.jpg","width":300,"height":56,"filesize":6777,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner-300x56.jpg"},"large":{"file":"Ajuts-post-baner-1024x192.jpg","width":1024,"height":192,"filesize":31612,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner-1024x192.jpg"},"thumbnail":{"file":"Ajuts-post-baner-150x150.jpg","width":150,"height":150,"filesize":6917,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner-150x150.jpg"},"medium_large":{"file":"Ajuts-post-baner-768x144.jpg","width":768,"height":144,"filesize":21369,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner-768x144.jpg"},"1536x1536":{"file":"Ajuts-post-baner-1536x288.jpg","width":1536,"height":288,"filesize":52819,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner-1536x288.jpg"},"thumb-300":{"file":"Ajuts-post-baner-300x250.jpg","width":300,"height":250,"filesize":13946,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner-300x250.jpg"},"thumb-200":{"file":"Ajuts-post-baner-200x150.jpg","width":200,"height":150,"filesize":8478,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner-200x150.jpg"},"full":{"file":"Ajuts-post-baner.jpg","width":1890,"height":354,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-content\/uploads\/usu1101\/2024\/03\/Ajuts-post-baner.jpg","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-json\/wp\/v2\/media\/10419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/inselstresturons\/wp-json\/wp\/v2\/comments?post=10419"}]}}