{"id":1955,"date":"2017-07-08T19:26:15","date_gmt":"2017-07-08T17:26:15","guid":{"rendered":"http:\/\/agora.xtec.cat\/ins25desetembre\/wp-content\/uploads\/usu1400\/2017\/07\/19429859_996018817167316_8246972024596598955_n.jpg"},"modified":"2017-07-08T19:26:15","modified_gmt":"2017-07-08T17:26:15","slug":"19429859_996018817167316_8246972024596598955_n","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/ins25desetembre\/19429859_996018817167316_8246972024596598955_n\/","title":{"rendered":"19429859_996018817167316_8246972024596598955_n"},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"class_list":["post-1955","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/ins25desetembre\/wp-content\/uploads\/usu1400\/2017\/07\/19429859_996018817167316_8246972024596598955_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/agora.xtec.cat\/ins25desetembre\/wp-content\/uploads\/usu1400\/2017\/07\/19429859_996018817167316_8246972024596598955_n-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/ins25desetembre\/wp-content\/uploads\/usu1400\/2017\/07\/19429859_996018817167316_8246972024596598955_n-225x300.jpg 225w, https:\/\/agora.xtec.cat\/ins25desetembre\/wp-content\/uploads\/usu1400\/2017\/07\/19429859_996018817167316_8246972024596598955_n.jpg 720w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href='https:\/\/agora.xtec.cat\/ins25desetembre\/wp-content\/uploads\/usu1400\/2017\/07\/19429859_996018817167316_8246972024596598955_n.jpg'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":720,"height":960,"file":"2017\/07\/19429859_996018817167316_8246972024596598955_n.jpg","sizes":{"thumbnail":{"file":"19429859_996018817167316_8246972024596598955_n-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ins25desetembre\/wp-content\/uploads\/usu1400\/2017\/07\/19429859_996018817167316_8246972024596598955_n-150x150.jpg"},"medium":{"file":"19429859_996018817167316_8246972024596598955_n-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ins25desetembre\/wp-content\/uploads\/usu1400\/2017\/07\/19429859_996018817167316_8246972024596598955_n-225x300.jpg"},"thumb-300":{"file":"19429859_996018817167316_8246972024596598955_n-300x250.jpg","width":300,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ins25desetembre\/wp-content\/uploads\/usu1400\/2017\/07\/19429859_996018817167316_8246972024596598955_n-300x250.jpg"},"thumb-200":{"file":"19429859_996018817167316_8246972024596598955_n-200x150.jpg","width":200,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ins25desetembre\/wp-content\/uploads\/usu1400\/2017\/07\/19429859_996018817167316_8246972024596598955_n-200x150.jpg"},"full":{"file":"19429859_996018817167316_8246972024596598955_n.jpg","width":720,"height":960,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ins25desetembre\/wp-content\/uploads\/usu1400\/2017\/07\/19429859_996018817167316_8246972024596598955_n.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agora.xtec.cat\/ins25desetembre\/wp-content\/uploads\/usu1400\/2017\/07\/19429859_996018817167316_8246972024596598955_n.jpg","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ins25desetembre\/wp-json\/wp\/v2\/media\/1955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ins25desetembre\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ins25desetembre\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ins25desetembre\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ins25desetembre\/wp-json\/wp\/v2\/comments?post=1955"}]}}