{"id":27494,"date":"2025-04-08T20:12:43","date_gmt":"2025-04-08T18:12:43","guid":{"rendered":"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/?p=27494"},"modified":"2025-04-08T20:14:35","modified_gmt":"2025-04-08T18:14:35","slug":"visita-upc-i-museu-del-ferrocarril","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/departaments-cicles\/electricitat\/visita-upc-i-museu-del-ferrocarril\/","title":{"rendered":"Visita UPC i Museu del Ferrocarril"},"content":{"rendered":"\r\n\t<div class=\"slideshow_container slideshow_container_style-light\" style=\"height: 300px; \" data-slideshow-id=\"27495\" data-style-name=\"style-light\" data-style-version=\"2.3.1\" >\r\n\r\n\t\t\t\t\t<div class=\"slideshow_loading_icon\"><\/div>\r\n\t\t\r\n\t\t<div class=\"slideshow_content\" style=\"display: none;\">\r\n\r\n\t\t\t<div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-content\/uploads\/usu1292\/2025\/04\/IMG-20250408-WA0008.jpg\" alt=\"IMG-20250408-WA0008\" width=\"2048\" height=\"1212\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG-20250408-WA0008<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-content\/uploads\/usu1292\/2025\/04\/IMG-20250408-WA0009.jpg\" alt=\"IMG-20250408-WA0009\" width=\"1384\" height=\"1687\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG-20250408-WA0009<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-content\/uploads\/usu1292\/2025\/04\/IMG-20250408-WA0003.jpg\" alt=\"IMG-20250408-WA0003\" width=\"2048\" height=\"1088\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG-20250408-WA0003<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-content\/uploads\/usu1292\/2025\/04\/IMG-20250408-WA0004.jpg\" alt=\"IMG-20250408-WA0004\" width=\"2048\" height=\"2048\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG-20250408-WA0004<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-content\/uploads\/usu1292\/2025\/04\/IMG-20250408-WA0005.jpg\" alt=\"IMG-20250408-WA0005\" width=\"2048\" height=\"2048\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG-20250408-WA0005<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-content\/uploads\/usu1292\/2025\/04\/IMG-20250408-WA0007.jpg\" alt=\"IMG-20250408-WA0007\" width=\"2048\" height=\"2048\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG-20250408-WA0007<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"slideshow_controlPanel slideshow_transparent\" style=\"display: none;\"><ul><li class=\"slideshow_togglePlay\" data-play-text=\"Visualitza\" data-pause-text=\"Pausa\"><\/li><\/ul><\/div>\r\n\r\n\t\t<div class=\"slideshow_button slideshow_previous slideshow_transparent\" role=\"button\" data-previous-text=\"Anterior\" style=\"display: none;\"><\/div>\r\n\t\t<div class=\"slideshow_button slideshow_next slideshow_transparent\" role=\"button\" data-next-text=\"Seg\u00fcent\" style=\"display: none;\"><\/div>\r\n\r\n\t\t<div class=\"slideshow_pagination\" style=\"display: none;\" data-go-to-text=\"V\u00e9s a la diapositiva\"><div class=\"slideshow_pagination_center\"><\/div><\/div>\r\n\r\n\t\t<!-- WordPress Slideshow Version 2.3.1 -->\r\n\r\n\t\t\t<\/div>\r\n\r\n\n<p>L&#8217;alumnat de 2n de Sistemes Electrot\u00e8cnics i Autom\u00e0tics ha visistat el Museu del Ferrocarril de Vilanova i la Geltr\u00fa, ens han explicat el funcionament de les m\u00e0quines de vapor, diesel i el\u00e8ctriques. Hem aprofitat tamb\u00e9 per visitar la UPC on ens han explicat com funciona la xarxa ferrovi\u00e0ria\u00a0 i les oportunitats de feina al sector.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;alumnat de 2n de Sistemes Electrot\u00e8cnics i Autom\u00e0tics ha visistat el Museu del Ferrocarril de Vilanova i la Geltr\u00fa, ens han explicat el funcionament de les m\u00e0quines de vapor, diesel i el\u00e8ctriques. Hem aprofitat tamb\u00e9 per visitar la UPC on ens han explicat com funciona la xarxa ferrovi\u00e0ria\u00a0 i les oportunitats de feina al sector.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1171,256,253,1093,1095],"tags":[],"class_list":["post-27494","post","type-post","status-publish","format-standard","hentry","category-activitats-del-curs-2024-2025","category-departaments-cicles","category-electricitat","category-installacions-electriques-i-automatiques","category-sistemes-electrotecnics-i-automatitzats"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-json\/wp\/v2\/posts\/27494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-json\/wp\/v2\/comments?post=27494"}],"version-history":[{"count":3,"href":"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-json\/wp\/v2\/posts\/27494\/revisions"}],"predecessor-version":[{"id":27498,"href":"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-json\/wp\/v2\/posts\/27494\/revisions\/27498"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-json\/wp\/v2\/media?parent=27494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-json\/wp\/v2\/categories?post=27494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesmarti-i-pol\/wp-json\/wp\/v2\/tags?post=27494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}