{"id":8772,"date":"2025-11-07T18:50:21","date_gmt":"2025-11-07T17:50:21","guid":{"rendered":"https:\/\/agora.xtec.cat\/iesllagostera\/?p=8772"},"modified":"2025-11-07T18:50:39","modified_gmt":"2025-11-07T17:50:39","slug":"activitats-alumnat-del-pfi-ptt","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/iesllagostera\/general\/activitats-alumnat-del-pfi-ptt\/","title":{"rendered":"Activitats diverses de l&#8217;alumnat del PFI-PTT"},"content":{"rendered":"<p>L&#8217;alumnat del PFI-PTT\u00a0 segueix fent activitats molt diverses. Despr\u00e9s de la primera sessi\u00f3 de Padrins\/es Lectors amb infants de i5 a l\u2019Escola Lacust\u00e0ria, de comen\u00e7ar les primeres pr\u00e0ctiques de desbrossadora a la zona de BTT de Llagostera, d&#8217;anar confeccionant el nostre i de fer teoria sobre maquin\u00e0ria i prevenci\u00f3 de riscos, avui ha visitat l\u2019ADF Gavarres a Sta Cristina d\u2019Aro. En Francesc ha explicat la seva feina de prevenci\u00f3 d\u2019incendis, neteja de boscos, maquin\u00e0ria, pirojardineria\u2026 Seguim treballant!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;alumnat del PFI-PTT\u00a0 segueix fent activitats molt diverses. Despr\u00e9s de la primera sessi\u00f3 de Padrins\/es Lectors amb infants de i5 a l\u2019Escola Lacust\u00e0ria, de comen\u00e7ar les primeres pr\u00e0ctiques de desbrossadora a la zona de BTT de Llagostera, d&#8217;anar confeccionant el nostre i de fer teoria&hellip;  <a href=\"https:\/\/agora.xtec.cat\/iesllagostera\/general\/activitats-alumnat-del-pfi-ptt\/\" title=\"Read Activitats diverses de l&#8217;alumnat del PFI-PTT\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":8773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1,184,29],"tags":[195],"class_list":["post-8772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-pfi-ptt-llagostera-auxiliar-de-vivers-i-jardins","category-portada","tag-pfi-ptt"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/iesllagostera\/wp-json\/wp\/v2\/posts\/8772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/iesllagostera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/iesllagostera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesllagostera\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesllagostera\/wp-json\/wp\/v2\/comments?post=8772"}],"version-history":[{"count":2,"href":"https:\/\/agora.xtec.cat\/iesllagostera\/wp-json\/wp\/v2\/posts\/8772\/revisions"}],"predecessor-version":[{"id":8775,"href":"https:\/\/agora.xtec.cat\/iesllagostera\/wp-json\/wp\/v2\/posts\/8772\/revisions\/8775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesllagostera\/wp-json\/wp\/v2\/media\/8773"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/iesllagostera\/wp-json\/wp\/v2\/media?parent=8772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesllagostera\/wp-json\/wp\/v2\/categories?post=8772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesllagostera\/wp-json\/wp\/v2\/tags?post=8772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}