{"id":5828,"date":"2021-03-19T15:34:19","date_gmt":"2021-03-19T14:34:19","guid":{"rendered":"http:\/\/agora.xtec.cat\/iesjoaquimmir\/?p=5828"},"modified":"2021-03-19T15:34:19","modified_gmt":"2021-03-19T14:34:19","slug":"a-lhora-de-pati-jocs-de-taula","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/iesjoaquimmir\/general\/a-lhora-de-pati-jocs-de-taula\/","title":{"rendered":"A l&#8217;hora de pati&#8230;Jocs de taula"},"content":{"rendered":"<p><strong>Aquesta setmana, a l&#8217;hora del pati, els alumnes han pogut gaudir del RAC\u00d3 DELS JOCS DE TAULA.<\/strong><\/p>\n<p><strong>Sabem que aquests jocs:<\/strong><\/p>\n<p><strong>\u00a0 \u00a0 \u00a0 \u00a0 &#8211; Ensenyen a respectar les normes<\/strong>.<\/p>\n<p><strong>\u00a0 \u00a0 \u00a0 \u00a0 &#8211; Milloren la capacitat d\u2019an\u00e0lisi<\/strong>.<strong>\u00a0 \u00a0 \u00a0 \u00a0 <\/strong><\/p>\n<p><strong>\u00a0 \u00a0 \u00a0 \u00a0 &#8211; Impulsen la cooperaci\u00f3 .<\/strong><\/p>\n<p><strong>\u00a0 \u00a0 \u00a0 \u00a0 &#8211; Ajuden a tolerar la frustraci\u00f3<\/strong>.<\/p>\n<p><strong>\u00a0 \u00a0 \u00a0 \u00a0 &#8211; Desenvolupen la capacitat resolutiva<\/strong>.<\/p>\n<p><strong>\u00a0I&#8230; S\u00f3n tan divertits com beneficiosos!<\/strong><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Aquesta setmana, a l&#8217;hora del pati, els alumnes han pogut gaudir del RAC\u00d3 DELS JOCS DE TAULA.<br \/>\nSabem que aquests jocs:<br \/>\n\u00a0 \u00a0 \u00a0 \u00a0 &#8211; Ensenyen a respectar les normes.<br \/>\n\u00a0 \u00a0 \u00a0 \u00a0 &#8211; Milloren la capacitat d\u2019an\u00e0lisi.\u00a0 \u00a0 \u00a0 \u00a0<br \/>\n\u00a0 \u00a0 \u00a0 \u00a0 &#8211;&hellip;  <a href=\"https:\/\/agora.xtec.cat\/iesjoaquimmir\/general\/a-lhora-de-pati-jocs-de-taula\/\" title=\"Read A l&#8217;hora de pati&#8230;Jocs de taula\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":27,"featured_media":5834,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3,1,29,116],"tags":[],"class_list":["post-5828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eso","category-general","category-portada","category-projectes"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/iesjoaquimmir\/wp-json\/wp\/v2\/posts\/5828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/iesjoaquimmir\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/iesjoaquimmir\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesjoaquimmir\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesjoaquimmir\/wp-json\/wp\/v2\/comments?post=5828"}],"version-history":[{"count":2,"href":"https:\/\/agora.xtec.cat\/iesjoaquimmir\/wp-json\/wp\/v2\/posts\/5828\/revisions"}],"predecessor-version":[{"id":5841,"href":"https:\/\/agora.xtec.cat\/iesjoaquimmir\/wp-json\/wp\/v2\/posts\/5828\/revisions\/5841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesjoaquimmir\/wp-json\/wp\/v2\/media\/5834"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/iesjoaquimmir\/wp-json\/wp\/v2\/media?parent=5828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesjoaquimmir\/wp-json\/wp\/v2\/categories?post=5828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesjoaquimmir\/wp-json\/wp\/v2\/tags?post=5828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}