{"id":4502,"date":"2022-04-25T13:49:54","date_gmt":"2022-04-25T11:49:54","guid":{"rendered":"https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001.jpg"},"modified":"2022-04-25T13:49:54","modified_gmt":"2022-04-25T11:49:54","slug":"photo-2022-04-22-12-27-001","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/iesblume\/photo-2022-04-22-12-27-001\/","title":{"rendered":"PHOTO-2022-04-22-12-27-00(1)"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"class_list":["post-4502","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001-300x225.jpg 300w, https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001-1024x768.jpg 1024w, https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001-768x576.jpg 768w, https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001-1536x1152.jpg 1536w, https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001-200x150.jpg 200w, https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":1200,"file":"2022\/04\/PHOTO-2022-04-22-12-27-001.jpg","sizes":{"medium":{"file":"PHOTO-2022-04-22-12-27-001-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001-300x225.jpg"},"large":{"file":"PHOTO-2022-04-22-12-27-001-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001-1024x768.jpg"},"thumbnail":{"file":"PHOTO-2022-04-22-12-27-001-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001-150x150.jpg"},"medium_large":{"file":"PHOTO-2022-04-22-12-27-001-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001-768x576.jpg"},"1536x1536":{"file":"PHOTO-2022-04-22-12-27-001-1536x1152.jpg","width":1536,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001-1536x1152.jpg"},"thumb-300":{"file":"PHOTO-2022-04-22-12-27-001-300x250.jpg","width":300,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001-300x250.jpg"},"thumb-200":{"file":"PHOTO-2022-04-22-12-27-001-200x150.jpg","width":200,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001-200x150.jpg"},"full":{"file":"PHOTO-2022-04-22-12-27-001.jpg","width":1600,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agora.xtec.cat\/iesblume\/wp-content\/uploads\/usu1242\/2022\/04\/PHOTO-2022-04-22-12-27-001.jpg","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/iesblume\/wp-json\/wp\/v2\/media\/4502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/iesblume\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/iesblume\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesblume\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/iesblume\/wp-json\/wp\/v2\/comments?post=4502"}]}}