{"id":600,"count":2,"description":"","link":"https:\/\/agora.xtec.cat\/iepepacolomer\/tag\/festes\/","name":"festes","slug":"festes","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/tags\/600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/posts?tags=600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}