{"id":5318,"date":"2021-05-20T20:37:30","date_gmt":"2021-05-20T18:37:30","guid":{"rendered":"http:\/\/agora.xtec.cat\/iepepacolomer\/?p=5318"},"modified":"2021-05-23T20:37:55","modified_gmt":"2021-05-23T18:37:55","slug":"finalitza-lspring-festival","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/iepepacolomer\/general\/finalitza-lspring-festival\/","title":{"rendered":"Finalitza l&#8217;Spring Festival"},"content":{"rendered":"<p>Aquest mat\u00ed els nens i les nenes representants d&#8217;angl\u00e8s dels cursos des de 2n de prim\u00e0ria fins a 1r d&#8217;ESO s&#8217;han reunit al pati per realitzar l&#8217;acte d&#8217;obertura de la caixa amb els codis que han anat aconseguint al llarg de la setmana.<\/p>\n<p>Hem obert la caixa a partir dels codis que hem obtingut superant els diferents reptes. Finalment, L&#8217;Ivan (5\u00e8 B) i la Nerea (4tB) han sigut els encarregats de portar la pe\u00e7a (amagada a l&#8217;interior de la caixa) a la Pla\u00e7a Catalunya i fer la nostra aportaci\u00f3 al trencaclosques gegant.<\/p>\n<div><\/div>\n<div>\r\n\t<div class=\"slideshow_container slideshow_container_style-light\" style=\"height: 500px; \" data-slideshow-id=\"5320\" data-style-name=\"style-light\" data-style-version=\"2.3.1\" >\r\n\r\n\t\t\t\t\t<div class=\"slideshow_loading_icon\"><\/div>\r\n\t\t\r\n\t\t<div class=\"slideshow_content\" style=\"display: none;\">\r\n\r\n\t\t\t<div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-content\/uploads\/usu1405\/2021\/05\/WhatsApp-Image-2021-05-20-at-14.23.51-7.jpeg\" alt=\"2021-05-20 Spring Fest 7\" width=\"1200\" height=\"1600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">2021-05-20 Spring Fest 7<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-content\/uploads\/usu1405\/2021\/05\/WhatsApp-Image-2021-05-20-at-14.23.51-1-1.jpeg\" alt=\"2021-05-20  Spring Fest 1\" width=\"2048\" height=\"946\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">2021-05-20  Spring Fest 1<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-content\/uploads\/usu1405\/2021\/05\/WhatsApp-Image-2021-05-20-at-14.23.51-6.jpeg\" alt=\"2021-05-20 Spring Fest 6\" width=\"1200\" height=\"1600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">2021-05-20 Spring Fest 6<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-content\/uploads\/usu1405\/2021\/05\/WhatsApp-Image-2021-05-20-at-14.23.51-4.jpeg\" alt=\"2021-05-20 Spring Fest 4\" width=\"2048\" height=\"1536\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">2021-05-20 Spring Fest 4<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-content\/uploads\/usu1405\/2021\/05\/WhatsApp-Image-2021-05-20-at-14.23.51-5.jpeg\" alt=\"2021-05-20 Spring Fest 5\" width=\"1024\" height=\"768\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">2021-05-20 Spring Fest 5<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-content\/uploads\/usu1405\/2021\/05\/WhatsApp-Image-2021-05-20-at-14.23.51-8.jpeg\" alt=\"2021-05-20 Spring Fest 8\" width=\"1600\" height=\"1200\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">2021-05-20 Spring Fest 8<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-content\/uploads\/usu1405\/2021\/05\/WhatsApp-Image-2021-05-20-at-14.23.52.jpeg\" alt=\"2021-05-20 Spring Fest\" width=\"1600\" height=\"1200\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">2021-05-20 Spring Fest<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"slideshow_controlPanel slideshow_transparent\" style=\"display: none;\"><ul><li class=\"slideshow_togglePlay\" data-play-text=\"Visualitza\" data-pause-text=\"Pausa\"><\/li><\/ul><\/div>\r\n\r\n\t\t<div class=\"slideshow_button slideshow_previous slideshow_transparent\" role=\"button\" data-previous-text=\"Anterior\" style=\"display: none;\"><\/div>\r\n\t\t<div class=\"slideshow_button slideshow_next slideshow_transparent\" role=\"button\" data-next-text=\"Seg\u00fcent\" style=\"display: none;\"><\/div>\r\n\r\n\t\t<div class=\"slideshow_pagination\" style=\"display: none;\" data-go-to-text=\"V\u00e9s a la diapositiva\"><div class=\"slideshow_pagination_center\"><\/div><\/div>\r\n\r\n\t\t<!-- WordPress Slideshow Version 2.3.1 -->\r\n\r\n\t\t\t<\/div>\r\n\r\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aquest mat\u00ed els nens i les nenes representants d&#8217;angl\u00e8s dels cursos des de 2n de prim\u00e0ria fins a 1r d&#8217;ESO s&#8217;han reunit al pati per realitzar l&#8217;acte d&#8217;obertura de la caixa amb els codis que han anat aconseguint al llarg de la setmana.<\/p>\n","protected":false},"author":1,"featured_media":5324,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1,4],"tags":[],"class_list":["post-5318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-portada"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/posts\/5318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/comments?post=5318"}],"version-history":[{"count":3,"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/posts\/5318\/revisions"}],"predecessor-version":[{"id":5332,"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/posts\/5318\/revisions\/5332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/media\/5324"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/media?parent=5318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/categories?post=5318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/iepepacolomer\/wp-json\/wp\/v2\/tags?post=5318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}