{"id":5575,"date":"2022-03-16T15:17:46","date_gmt":"2022-03-16T14:17:46","guid":{"rendered":"https:\/\/agora.xtec.cat\/escolapinyana\/?p=5575"},"modified":"2022-03-16T15:18:35","modified_gmt":"2022-03-16T14:18:35","slug":"a-primer-fem-racons-de-llengua","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/escolapinyana\/portada\/a-primer-fem-racons-de-llengua\/","title":{"rendered":"A PRIMER FEM RACONS DE LLENGUA"},"content":{"rendered":"<p style=\"text-align: justify;\">Els i les alumnes de primer de Cicle Inicial han comen\u00e7at la Tanda 2 de racons<br \/>\nde catal\u00e0. En aquesta tanda ja hem introdu\u00eft les normes per fer els racons i a<br \/>\ncada rac\u00f3 de treball les instruccions del qu\u00e8 han de fer.<\/p>\n<p style=\"text-align: justify;\">Tenen 5 racons per triar i a cada sessi\u00f3 en trien un per fer, aquests s\u00f3n:<br \/>\ncomprensi\u00f3 lectora, expressi\u00f3 escrita, expressi\u00f3 oral, l\u00fadic per treballar<br \/>\nl\u2019atenci\u00f3 i les TIC amb les tauletes on la feina la troben en una aula virtual i dins<br \/>\nd\u2019aquesta aprenen mitjan\u00e7ant l\u2019aplicaci\u00f3 del symbaloo.<\/p>\n<p style=\"text-align: justify;\">Aqu\u00ed us en deixem una petita mostra:<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/GUkMurBia4M\" width=\"560\" height=\"314\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Els i les alumnes de primer de Cicle Inicial han comen\u00e7at la Tanda 2 de racons<br \/>\nde catal\u00e0. En aquesta tanda ja hem introdu\u00eft les normes per fer els racons i a<br \/>\ncada rac\u00f3 de treball les instruccions del qu\u00e8 han de fer.<br \/>\nTenen 5 racons per triar&hellip;  <a href=\"https:\/\/agora.xtec.cat\/escolapinyana\/portada\/a-primer-fem-racons-de-llengua\/\" title=\"Read A PRIMER FEM RACONS DE LLENGUA\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":4,"featured_media":5576,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[109,62,4,5],"tags":[128,150],"class_list":["post-5575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-de-classe-1r","category-cicle-inicial-primaria","category-portada","category-primaria","tag-cicle-inicial","tag-primer"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolapinyana\/wp-json\/wp\/v2\/posts\/5575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolapinyana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolapinyana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolapinyana\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolapinyana\/wp-json\/wp\/v2\/comments?post=5575"}],"version-history":[{"count":3,"href":"https:\/\/agora.xtec.cat\/escolapinyana\/wp-json\/wp\/v2\/posts\/5575\/revisions"}],"predecessor-version":[{"id":5585,"href":"https:\/\/agora.xtec.cat\/escolapinyana\/wp-json\/wp\/v2\/posts\/5575\/revisions\/5585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolapinyana\/wp-json\/wp\/v2\/media\/5576"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/escolapinyana\/wp-json\/wp\/v2\/media?parent=5575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolapinyana\/wp-json\/wp\/v2\/categories?post=5575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolapinyana\/wp-json\/wp\/v2\/tags?post=5575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}