{"id":3520,"date":"2022-01-24T09:30:15","date_gmt":"2022-01-24T08:30:15","guid":{"rendered":"https:\/\/agora.xtec.cat\/escolamontserratina\/?p=3520"},"modified":"2022-06-05T23:44:25","modified_gmt":"2022-06-05T21:44:25","slug":"lesquema-corporal","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/escolamontserratina\/general\/lesquema-corporal\/","title":{"rendered":"L&#8217;ESQUEMA CORPORAL"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">A l\u2019etapa d&#8217;Educaci\u00f3 Infantil, a partir de l\u2019Esquema Corporal realitzat als tres nivells, podem veure l\u2019evoluci\u00f3 de l\u2019infant gr\u00e0cies a la seva representaci\u00f3.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El coneixement del propi cos \u00e9s un dels aspectes que ens ajuden a veure l\u2019evoluci\u00f3 de l\u2019infant que est\u00e0 condicionat al ritme i al desenvolupament de cadasc\u00fa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Saber les parts del cos, on s\u00f3n, per qu\u00e8 serveixen, tenir consci\u00e8ncia del que un \u00e9s capa\u00e7 de fer amb el seu cos i anticipar els possibles perills s\u00f3n aspectes que van incorporant poc a poc, a mida que es van fent grans.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Abans de la realitzaci\u00f3 d\u2019aquest dibuix desenvolupem activitats diverses per a la seva adquisici\u00f3 com la psicomotricitat grossa i fina, i a trav\u00e9s de diverses experimentacions amb el nostre cos descobrim els sentits.<\/span><\/p>\n\r\n\t<div class=\"slideshow_container slideshow_container_style-light\" style=\"height: 500px; \" data-slideshow-id=\"3522\" data-style-name=\"style-light\" data-style-version=\"2.3.1\" >\r\n\r\n\t\t\t\t\t<div class=\"slideshow_loading_icon\"><\/div>\r\n\t\t\r\n\t\t<div class=\"slideshow_content\" style=\"display: none;\">\r\n\r\n\t\t\t<div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-content\/uploads\/usu275\/2022\/01\/1_resultado-scaled-e1642970294201.jpg\" alt=\"1.\" width=\"375\" height=\"500\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">1.<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-content\/uploads\/usu275\/2022\/01\/2_resultado-scaled-e1642970267665.jpg\" alt=\"2.\" width=\"400\" height=\"533\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">2.<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-content\/uploads\/usu275\/2022\/01\/3_resultado-scaled-e1642970621603.jpg\" alt=\"3.\" width=\"400\" height=\"534\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">3.<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-content\/uploads\/usu275\/2022\/01\/4_resultado-scaled-e1642970598326.jpg\" alt=\"4.\" width=\"400\" height=\"534\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">4.<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-content\/uploads\/usu275\/2022\/01\/5_resultado-scaled-e1642970556175.jpg\" alt=\"5\" width=\"400\" height=\"533\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">5<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"slideshow_controlPanel slideshow_transparent\" style=\"display: none;\"><ul><li class=\"slideshow_togglePlay\" data-play-text=\"Visualitza\" data-pause-text=\"Pausa\"><\/li><\/ul><\/div>\r\n\r\n\t\t<div class=\"slideshow_button slideshow_previous slideshow_transparent\" role=\"button\" data-previous-text=\"Anterior\" style=\"display: none;\"><\/div>\r\n\t\t<div class=\"slideshow_button slideshow_next slideshow_transparent\" role=\"button\" data-next-text=\"Seg\u00fcent\" style=\"display: none;\"><\/div>\r\n\r\n\t\t<div class=\"slideshow_pagination\" style=\"display: none;\" data-go-to-text=\"V\u00e9s a la diapositiva\"><div class=\"slideshow_pagination_center\"><\/div><\/div>\r\n\r\n\t\t<!-- WordPress Slideshow Version 2.3.1 -->\r\n\r\n\t\t\t<\/div>\r\n\r\n\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A l\u2019etapa d&#8217;Educaci\u00f3 Infantil, a partir de l\u2019Esquema Corporal realitzat als tres nivells, podem veure l\u2019evoluci\u00f3 de l\u2019infant gr\u00e0cies a la seva representaci\u00f3. El coneixement del propi cos \u00e9s un dels aspectes que ens ajuden a veure l\u2019evoluci\u00f3 de l\u2019infant que est\u00e0 condicionat al ritme i al desenvolupament de cadasc\u00fa. Saber les parts del cos, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1,3,8,9,2,4],"tags":[],"class_list":["post-3520","post","type-post","status-publish","format-standard","hentry","category-general","category-inf3","category-inf4","category-inf5","category-infantil","category-portada"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-json\/wp\/v2\/posts\/3520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-json\/wp\/v2\/comments?post=3520"}],"version-history":[{"count":4,"href":"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-json\/wp\/v2\/posts\/3520\/revisions"}],"predecessor-version":[{"id":3530,"href":"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-json\/wp\/v2\/posts\/3520\/revisions\/3530"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-json\/wp\/v2\/media?parent=3520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-json\/wp\/v2\/categories?post=3520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontserratina\/wp-json\/wp\/v2\/tags?post=3520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}