{"id":2230,"date":"2020-10-15T15:45:16","date_gmt":"2020-10-15T13:45:16","guid":{"rendered":"https:\/\/agora.xtec.cat\/escolamontbou\/?p=2230"},"modified":"2021-11-06T00:38:41","modified_gmt":"2021-11-05T23:38:41","slug":"pinzellades-de-van-gogh-a-1r","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/escolamontbou\/ci\/pinzellades-de-van-gogh-a-1r\/","title":{"rendered":"Pinzellades d&#8217;art de Van Gogh a 1r"},"content":{"rendered":"\r\n\t<div class=\"slideshow_container slideshow_container_style-light\" style=\"height: 300px; \" data-slideshow-id=\"2270\" data-style-name=\"style-light\" data-style-version=\"2.3.1\" >\r\n\r\n\t\t\t\t\t<div class=\"slideshow_loading_icon\"><\/div>\r\n\t\t\r\n\t\t<div class=\"slideshow_content\" style=\"display: none;\">\r\n\r\n\t\t\t<div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2020\/11\/IMG_3133-e1605625970572.jpg\" alt=\"IMG_3133\" width=\"3024\" height=\"4032\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3133<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2020\/11\/IMG_3132-2-e1605625984706.jpg\" alt=\"IMG_3132\" width=\"3024\" height=\"4032\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3132<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2020\/11\/IMG_3127-1-e1605625995404.jpg\" alt=\"IMG_3127\" width=\"3024\" height=\"4032\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3127<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2020\/11\/IMG_3126-1-e1605626006216.jpg\" alt=\"IMG_3126\" width=\"3024\" height=\"4032\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3126<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2020\/11\/IMG_3125-e1605626017142.jpg\" alt=\"IMG_3125\" width=\"3024\" height=\"4032\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3125<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2020\/11\/IMG_3122.jpg\" alt=\"IMG_3122\" width=\"4032\" height=\"3024\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3122<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2020\/11\/IMG_3121-e1605626026456.jpg\" alt=\"IMG_3121\" width=\"3024\" height=\"4032\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3121<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2020\/11\/IMG_3120-e1605626038796.jpg\" alt=\"IMG_3120\" width=\"3024\" height=\"4032\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3120<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2020\/11\/IMG_3119.jpg\" alt=\"IMG_3119\" width=\"4032\" height=\"3024\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3119<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2020\/11\/ERDE8843-4.jpg\" alt=\"ERDE8843\" width=\"2048\" height=\"2048\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">ERDE8843<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"slideshow_controlPanel slideshow_transparent\" style=\"display: none;\"><ul><li class=\"slideshow_togglePlay\" data-play-text=\"Visualitza\" data-pause-text=\"Pausa\"><\/li><\/ul><\/div>\r\n\r\n\t\t<div class=\"slideshow_button slideshow_previous slideshow_transparent\" role=\"button\" data-previous-text=\"Anterior\" style=\"display: none;\"><\/div>\r\n\t\t<div class=\"slideshow_button slideshow_next slideshow_transparent\" role=\"button\" data-next-text=\"Seg\u00fcent\" style=\"display: none;\"><\/div>\r\n\r\n\t\t<div class=\"slideshow_pagination\" style=\"display: none;\" data-go-to-text=\"V\u00e9s a la diapositiva\"><div class=\"slideshow_pagination_center\"><\/div><\/div>\r\n\r\n\t\t<!-- WordPress Slideshow Version 2.3.1 -->\r\n\r\n\t\t\t<\/div>\r\n\r\n\n<p>\ud83c\udf08\ud83d\udc68\ud83c\udffb\u200d\ud83c\udfa8\ud83d\udc71\ud83c\udffb\u200d\u2642\ufe0f\ud83c\udfa8\ud83c\udfa8#escolamontbou#pl\u00e0sticamontbou#cicleinicialmontbou<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83c\udf08\ud83d\udc68\ud83c\udffb\u200d\ud83c\udfa8\ud83d\udc71\ud83c\udffb\u200d\u2642\ufe0f\ud83c\udfa8\ud83c\udfa8#escolamontbou#pl\u00e0sticamontbou#cicleinicialmontbou<\/p>\n","protected":false},"author":8,"featured_media":2382,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[10,5,108,107,94],"tags":[],"class_list":["post-2230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1r","category-ci","category-fotos-curs-20-21","category-fotos-escola","category-pagina-dinici"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/posts\/2230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/comments?post=2230"}],"version-history":[{"count":3,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/posts\/2230\/revisions"}],"predecessor-version":[{"id":2474,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/posts\/2230\/revisions\/2474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/media\/2382"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/media?parent=2230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/categories?post=2230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/tags?post=2230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}