{"id":10767,"date":"2025-05-14T16:55:57","date_gmt":"2025-05-14T14:55:57","guid":{"rendered":"https:\/\/agora.xtec.cat\/escolamontbou\/?p=10767"},"modified":"2025-05-14T16:57:47","modified_gmt":"2025-05-14T14:57:47","slug":"a-5e-juguem-a-tennis-%f0%9f%8e%be%f0%9f%8e%be%f0%9f%8e%be","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/escolamontbou\/cicle-superior\/5e\/a-5e-juguem-a-tennis-%f0%9f%8e%be%f0%9f%8e%be%f0%9f%8e%be\/","title":{"rendered":"L\u2019alumnat de 5\u00e8 \ud83d\udc6b juguem a tennis! \ud83c\udfbe\ud83c\udfbe\ud83c\udfbe\ud83c\udff8\ud83c\udff8\ud83c\udff8"},"content":{"rendered":"\r\n\t<div class=\"slideshow_container slideshow_container_style-light\" style=\"height: 300px; \" data-slideshow-id=\"10752\" data-style-name=\"style-light\" data-style-version=\"2.3.1\" >\r\n\r\n\t\t\t\t\t<div class=\"slideshow_loading_icon\"><\/div>\r\n\t\t\r\n\t\t<div class=\"slideshow_content\" style=\"display: none;\">\r\n\r\n\t\t\t<div class=\"slideshow_view\">\r\n\t<div class=\"slideshow_slide slideshow_slide_video\">\r\n\t\t<div class=\"slideshow_slide_video_id\" style=\"display: none;\" data-show-related-videos=\"0\">JD_8Wo97xM8<\/div>\r\n\t<\/div>\r\n<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2025\/05\/2-1.jpg\" alt=\"2\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2025\/05\/3-1.jpg\" alt=\"3\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2025\/05\/4-1.jpg\" alt=\"4\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2025\/05\/5-1.jpg\" alt=\"5\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2025\/05\/6-2.jpg\" alt=\"6\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2025\/05\/7-2.jpg\" alt=\"7\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2025\/05\/8-1.jpg\" alt=\"8\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2025\/05\/9-1.jpg\" alt=\"9\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2025\/05\/10-2.jpg\" alt=\"10\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2025\/05\/11-2.jpg\" alt=\"11\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2025\/05\/12-1.jpg\" alt=\"12\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2025\/05\/13.jpg\" alt=\"13\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolamontbou\/wp-content\/uploads\/usu309\/2025\/05\/14.jpg\" alt=\"14\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"slideshow_controlPanel slideshow_transparent\" style=\"display: none;\"><ul><li class=\"slideshow_togglePlay\" data-play-text=\"Visualitza\" data-pause-text=\"Pausa\"><\/li><\/ul><\/div>\r\n\r\n\t\t<div class=\"slideshow_button slideshow_previous slideshow_transparent\" role=\"button\" data-previous-text=\"Anterior\" style=\"display: none;\"><\/div>\r\n\t\t<div class=\"slideshow_button slideshow_next slideshow_transparent\" role=\"button\" data-next-text=\"Seg\u00fcent\" style=\"display: none;\"><\/div>\r\n\r\n\t\t<div class=\"slideshow_pagination\" style=\"display: none;\" data-go-to-text=\"V\u00e9s a la diapositiva\"><div class=\"slideshow_pagination_center\"><\/div><\/div>\r\n\r\n\t\t<!-- WordPress Slideshow Version 2.3.1 -->\r\n\r\n\t\t\t<\/div>\r\n\r\n\n<p>L\u2019alumnat de 5\u00e8 \ud83d\udc6b de prim\u00e0ria hem practicat l\u2019esport del tennis \ud83c\udff8 a les sessions d\u2019Educaci\u00f3 F\u00edsica \ud83c\udfcb\ud83c\udffb\u200d\u2640\ufe0f.<br \/>\nAquest esport \ud83c\udfbe ens permet desenvolupar les nostres habilitats amb la manipulaci\u00f3 d\u2019objectes \ud83e\udd39 i la coordinaci\u00f3 ull-m\u00e0. \ud83d\ude4c\ud83c\udffb\ud83d\udc40<br \/>\nEstem progressant i cada vegada fem m\u00e9s cops seguits! \ud83d\udc4f\ud83c\udffb\ud83d\udc4f\ud83c\udffb\ud83d\udc4f\ud83c\udffb\ud83d\udd1d\ud83d\ude4c\ud83c\udffb<br \/>\n<a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz _aa9_ _a6hd\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.instagram.com\/explore\/tags\/escolamontbou\/\">#escolamontbou<\/a> <a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz _aa9_ _a6hd\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.instagram.com\/explore\/tags\/educaci%C3%B3f%C3%ADsicamontbou\/\">#educaci\u00f3f\u00edsicamontbou<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019alumnat de 5\u00e8 \ud83d\udc6b de prim\u00e0ria hem practicat l\u2019esport del tennis \ud83c\udff8 a les sessions d\u2019Educaci\u00f3 F\u00edsica \ud83c\udfcb\ud83c\udffb\u200d\u2640\ufe0f. Aquest esport \ud83c\udfbe ens permet desenvolupar les nostres habilitats amb la manipulaci\u00f3 d\u2019objectes \ud83e\udd39 i la coordinaci\u00f3 ull-m\u00e0. \ud83d\ude4c\ud83c\udffb\ud83d\udc40 Estem progressant i cada vegada fem m\u00e9s cops seguits! \ud83d\udc4f\ud83c\udffb\ud83d\udc4f\ud83c\udffb\ud83d\udc4f\ud83c\udffb\ud83d\udd1d\ud83d\ude4c\ud83c\udffb #escolamontbou #educaci\u00f3f\u00edsicamontbou<\/p>\n","protected":false},"author":1,"featured_media":10765,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[14,81,135,107,94],"tags":[],"class_list":["post-10767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-5e","category-cicle-superior","category-fotos-curs-24-25","category-fotos-escola","category-pagina-dinici"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/posts\/10767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/comments?post=10767"}],"version-history":[{"count":4,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/posts\/10767\/revisions"}],"predecessor-version":[{"id":10771,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/posts\/10767\/revisions\/10771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/media\/10765"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/media?parent=10767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/categories?post=10767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamontbou\/wp-json\/wp\/v2\/tags?post=10767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}