{"id":2757,"date":"2023-10-11T12:56:58","date_gmt":"2023-10-11T10:56:58","guid":{"rendered":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5.jpg"},"modified":"2023-10-11T12:56:58","modified_gmt":"2023-10-11T10:56:58","slug":"2283ca30-14cb-4d4d-87ae-c9246ca5b1b5","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5\/","title":{"rendered":"2283ca30-14cb-4d4d-87ae-c9246ca5b1b5"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"class_list":["post-2757","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-225x300.jpg 225w, https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-768x1024.jpg 768w, https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-1152x1536.jpg 1152w, https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5.jpg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href='https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5.jpg'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":1600,"file":"2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5.jpg","sizes":{"medium":{"file":"2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-225x300.jpg"},"large":{"file":"2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-768x1024.jpg"},"thumbnail":{"file":"2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-150x150.jpg"},"medium_large":{"file":"2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-768x1024.jpg"},"1536x1536":{"file":"2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-1152x1536.jpg","width":1152,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-1152x1536.jpg"},"thumb-300":{"file":"2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-300x250.jpg","width":300,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-300x250.jpg"},"thumb-200":{"file":"2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-200x150.jpg","width":200,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5-200x150.jpg"},"full":{"file":"2283ca30-14cb-4d4d-87ae-c9246ca5b1b5.jpg","width":1200,"height":1600,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/10\/2283ca30-14cb-4d4d-87ae-c9246ca5b1b5.jpg","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-json\/wp\/v2\/media\/2757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-json\/wp\/v2\/comments?post=2757"}]}}