{"id":2524,"date":"2023-05-23T12:40:38","date_gmt":"2023-05-23T10:40:38","guid":{"rendered":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31.jpg"},"modified":"2023-05-23T12:40:38","modified_gmt":"2023-05-23T10:40:38","slug":"1a038ed0-e968-49de-9839-05e492b4cb31","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/1a038ed0-e968-49de-9839-05e492b4cb31\/","title":{"rendered":"1a038ed0-e968-49de-9839-05e492b4cb31"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"class_list":["post-2524","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31-300x225.jpg 300w, https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31-1024x768.jpg 1024w, https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31-768x576.jpg 768w, https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31-1536x1152.jpg 1536w, https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31-200x150.jpg 200w, https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href='https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31.jpg'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2048,"height":1536,"file":"2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31.jpg","sizes":{"medium":{"file":"1a038ed0-e968-49de-9839-05e492b4cb31-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31-300x225.jpg"},"large":{"file":"1a038ed0-e968-49de-9839-05e492b4cb31-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31-1024x768.jpg"},"thumbnail":{"file":"1a038ed0-e968-49de-9839-05e492b4cb31-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31-150x150.jpg"},"medium_large":{"file":"1a038ed0-e968-49de-9839-05e492b4cb31-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31-768x576.jpg"},"1536x1536":{"file":"1a038ed0-e968-49de-9839-05e492b4cb31-1536x1152.jpg","width":1536,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31-1536x1152.jpg"},"thumb-300":{"file":"1a038ed0-e968-49de-9839-05e492b4cb31-300x250.jpg","width":300,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31-300x250.jpg"},"thumb-200":{"file":"1a038ed0-e968-49de-9839-05e492b4cb31-200x150.jpg","width":200,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31-200x150.jpg"},"full":{"file":"1a038ed0-e968-49de-9839-05e492b4cb31.jpg","width":2048,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-content\/uploads\/usu1988\/2023\/05\/1a038ed0-e968-49de-9839-05e492b4cb31.jpg","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-json\/wp\/v2\/media\/2524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolamaredelamerce-santramon\/wp-json\/wp\/v2\/comments?post=2524"}]}}