{"id":7986,"date":"2025-11-07T20:53:08","date_gmt":"2025-11-07T19:53:08","guid":{"rendered":"https:\/\/agora.xtec.cat\/escolallebetx\/?p=7986"},"modified":"2026-03-27T18:19:57","modified_gmt":"2026-03-27T17:19:57","slug":"activitat-dels-coales","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/escolallebetx\/colla-marinera\/activitat-dels-coales\/","title":{"rendered":"Activitat dels coales, 1r"},"content":{"rendered":"<p>Avui hem anat al terrat de la nostra escola per poder mesurar. Una de les curiositats que ha sortit mentre busc\u00e0vem informaci\u00f3 sobre on viuen i qu\u00e8 mengen ha estat buscar quina \u00e9s l&#8217;al\u00e7ada d&#8217;un arbre d&#8217;eucaliptus. Hem trobat que poden mesurar 20 metres i arribar fins al 70 metres. Aprofitant que el terrat \u00e9s molt llarg hem mesurat els 20 metres i hem comprovat que necessitar\u00edem 17 persones de la classe per arribar a fer aquest al\u00e7ada. Tamb\u00e9 hem comprovat quantes passes de les nostres hav\u00edem de fer per rec\u00f2rrer aquesta dist\u00e0ncia.<\/p>\n\r\n\t<div class=\"slideshow_container slideshow_container_style-light\" style=\"height: 500px; \" data-slideshow-id=\"8005\" data-style-name=\"style-light\" data-style-version=\"2.3.1\" >\r\n\r\n\t\t\t\t\t<div class=\"slideshow_loading_icon\"><\/div>\r\n\t\t\r\n\t\t<div class=\"slideshow_content\" style=\"display: none;\">\r\n\r\n\t\t\t<div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolallebetx\/wp-content\/uploads\/usu1343\/2025\/11\/N34.jpg\" alt=\"N34\" width=\"1440\" height=\"1920\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">N34<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolallebetx\/wp-content\/uploads\/usu1343\/2025\/11\/N33.jpg\" alt=\"N33\" width=\"1440\" height=\"1920\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">N33<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolallebetx\/wp-content\/uploads\/usu1343\/2025\/11\/N32.jpg\" alt=\"N32\" width=\"1440\" height=\"1920\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">N32<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolallebetx\/wp-content\/uploads\/usu1343\/2025\/11\/N31.jpg\" alt=\"N31\" width=\"1920\" height=\"1440\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">N31<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolallebetx\/wp-content\/uploads\/usu1343\/2025\/11\/N29.jpg\" alt=\"N29\" width=\"1440\" height=\"1920\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">N29<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolallebetx\/wp-content\/uploads\/usu1343\/2025\/11\/N26.jpg\" alt=\"N26\" width=\"1440\" height=\"1920\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">N26<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolallebetx\/wp-content\/uploads\/usu1343\/2025\/11\/N23.jpg\" alt=\"N23\" width=\"1440\" height=\"1920\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">N23<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolallebetx\/wp-content\/uploads\/usu1343\/2025\/11\/N22.jpg\" alt=\"N22\" width=\"1920\" height=\"1440\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">N22<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolallebetx\/wp-content\/uploads\/usu1343\/2025\/11\/N21.jpg\" alt=\"N21\" width=\"1440\" height=\"1920\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">N21<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolallebetx\/wp-content\/uploads\/usu1343\/2025\/11\/N20.jpg\" alt=\"N20\" width=\"1440\" height=\"1920\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">N20<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolallebetx\/wp-content\/uploads\/usu1343\/2025\/11\/N19.jpg\" alt=\"N19\" width=\"1440\" height=\"1920\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">N19<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolallebetx\/wp-content\/uploads\/usu1343\/2025\/11\/N16.jpg\" alt=\"N16\" width=\"1440\" height=\"1920\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">N16<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/escolallebetx\/wp-content\/uploads\/usu1343\/2025\/11\/N15-scaled.jpg\" alt=\"N15\" width=\"1920\" height=\"2560\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">N15<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"slideshow_controlPanel slideshow_transparent\" style=\"display: none;\"><ul><li class=\"slideshow_togglePlay\" data-play-text=\"Visualitza\" data-pause-text=\"Pausa\"><\/li><\/ul><\/div>\r\n\r\n\t\t<div class=\"slideshow_button slideshow_previous slideshow_transparent\" role=\"button\" data-previous-text=\"Anterior\" style=\"display: none;\"><\/div>\r\n\t\t<div class=\"slideshow_button slideshow_next slideshow_transparent\" role=\"button\" data-next-text=\"Seg\u00fcent\" style=\"display: none;\"><\/div>\r\n\r\n\t\t<div class=\"slideshow_pagination\" style=\"display: none;\" data-go-to-text=\"V\u00e9s a la diapositiva\"><div class=\"slideshow_pagination_center\"><\/div><\/div>\r\n\r\n\t\t<!-- WordPress Slideshow Version 2.3.1 -->\r\n\r\n\t\t\t<\/div>\r\n\r\n\n<p><a href=\"https:\/\/drive.google.com\/file\/d\/1i3J6RNwVYr6iBOrQV7vXdr0Efc3GtRNM\/view?usp=sharing\">https:\/\/drive.google.com\/file\/d\/1i3J6RNwVYr6iBOrQV7vXdr0Efc3GtRNM\/view?usp=sharing<\/a><\/p>\n<p><a href=\"https:\/\/drive.google.com\/file\/d\/18vR55WAfQW9JG6JDlEssZFK6TcMgpV3o\/view?usp=sharing\">https:\/\/drive.google.com\/file\/d\/18vR55WAfQW9JG6JDlEssZFK6TcMgpV3o\/view?usp=sharing<\/a><\/p>\n<p><a href=\"https:\/\/drive.google.com\/file\/d\/1xr_-ubbX7l5g3GLNofBXcoBq6DEejnfJ\/view?usp=sharing\">https:\/\/drive.google.com\/file\/d\/1xr_-ubbX7l5g3GLNofBXcoBq6DEejnfJ\/view?usp=sharing<\/a><\/p>\n<p><a href=\"https:\/\/drive.google.com\/file\/d\/1ZL_8HlI-zrzhJyil3ky3LoWjesGFm0Bk\/view?usp=sharing\">https:\/\/drive.google.com\/file\/d\/1ZL_8HlI-zrzhJyil3ky3LoWjesGFm0Bk\/view?usp=sharing<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avui hem anat al terrat de la nostra escola per poder mesurar. Una de les curiositats que ha sortit mentre busc\u00e0vem informaci\u00f3 sobre on viuen i qu\u00e8 mengen ha estat buscar quina \u00e9s l&#8217;al\u00e7ada d&#8217;un arbre d&#8217;eucaliptus. Hem trobat que poden mesurar 20 metres i arribar fins al 70 metres. Aprofitant que el terrat \u00e9s [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[307],"tags":[],"class_list":["post-7986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colla-marinera"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolallebetx\/wp-json\/wp\/v2\/posts\/7986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolallebetx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolallebetx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolallebetx\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolallebetx\/wp-json\/wp\/v2\/comments?post=7986"}],"version-history":[{"count":6,"href":"https:\/\/agora.xtec.cat\/escolallebetx\/wp-json\/wp\/v2\/posts\/7986\/revisions"}],"predecessor-version":[{"id":8399,"href":"https:\/\/agora.xtec.cat\/escolallebetx\/wp-json\/wp\/v2\/posts\/7986\/revisions\/8399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolallebetx\/wp-json\/wp\/v2\/media\/8003"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/escolallebetx\/wp-json\/wp\/v2\/media?parent=7986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolallebetx\/wp-json\/wp\/v2\/categories?post=7986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolallebetx\/wp-json\/wp\/v2\/tags?post=7986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}