{"id":2815,"date":"2024-06-11T10:08:11","date_gmt":"2024-06-11T08:08:11","guid":{"rendered":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416.jpg"},"modified":"2024-06-11T10:08:11","modified_gmt":"2024-06-11T08:08:11","slug":"img_20240610_123416","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/general\/visitem-lescola-de-la-celia\/attachment\/img_20240610_123416\/","title":{"rendered":"IMG_20240610_123416"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"class_list":["post-2815","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416-225x300.jpg 225w, https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416-768x1024.jpg 768w, https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416-1152x1536.jpg 1152w, https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416.jpg 1530w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href='https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416.jpg'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1530,"height":2040,"file":"2024\/06\/IMG_20240610_123416.jpg","filesize":178780,"sizes":{"medium":{"file":"IMG_20240610_123416-225x300.jpg","width":225,"height":300,"filesize":10720,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416-225x300.jpg"},"large":{"file":"IMG_20240610_123416-768x1024.jpg","width":768,"height":1024,"filesize":68188,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416-768x1024.jpg"},"thumbnail":{"file":"IMG_20240610_123416-150x150.jpg","width":150,"height":150,"filesize":4977,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416-150x150.jpg"},"medium_large":{"file":"IMG_20240610_123416-768x1024.jpg","width":768,"height":1024,"filesize":68188,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416-768x1024.jpg"},"1536x1536":{"file":"IMG_20240610_123416-1152x1536.jpg","width":1152,"height":1536,"filesize":135333,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416-1152x1536.jpg"},"thumb-300":{"file":"IMG_20240610_123416-300x250.jpg","width":300,"height":250,"filesize":10415,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416-300x250.jpg"},"thumb-200":{"file":"IMG_20240610_123416-200x150.jpg","width":200,"height":150,"filesize":5590,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416-200x150.jpg"},"full":{"file":"IMG_20240610_123416.jpg","width":1530,"height":2040,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2806,"source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/06\/IMG_20240610_123416.jpg","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-json\/wp\/v2\/media\/2815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-json\/wp\/v2\/comments?post=2815"}]}}