{"id":2319,"date":"2024-04-10T16:16:15","date_gmt":"2024-04-10T14:16:15","guid":{"rendered":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309.jpg"},"modified":"2024-04-10T16:16:15","modified_gmt":"2024-04-10T14:16:15","slug":"img_20240410_105309","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/general\/excursio-a-lescola-itaca\/attachment\/img_20240410_105309\/","title":{"rendered":"IMG_20240410_105309"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"class_list":["post-2319","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309-300x225.jpg 300w, https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309-1024x768.jpg 1024w, https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309-768x576.jpg 768w, https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309-1536x1152.jpg 1536w, https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309-200x150.jpg 200w, https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309.jpg 2040w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href='https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309.jpg'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2040,"height":1530,"file":"2024\/04\/IMG_20240410_105309.jpg","filesize":368331,"sizes":{"medium":{"file":"IMG_20240410_105309-300x225.jpg","width":300,"height":225,"filesize":15964,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309-300x225.jpg"},"large":{"file":"IMG_20240410_105309-1024x768.jpg","width":1024,"height":768,"filesize":127511,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309-1024x768.jpg"},"thumbnail":{"file":"IMG_20240410_105309-150x150.jpg","width":150,"height":150,"filesize":6536,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309-150x150.jpg"},"medium_large":{"file":"IMG_20240410_105309-768x576.jpg","width":768,"height":576,"filesize":76339,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309-768x576.jpg"},"1536x1536":{"file":"IMG_20240410_105309-1536x1152.jpg","width":1536,"height":1152,"filesize":259017,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309-1536x1152.jpg"},"thumb-300":{"file":"IMG_20240410_105309-300x250.jpg","width":300,"height":250,"filesize":16801,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309-300x250.jpg"},"thumb-200":{"file":"IMG_20240410_105309-200x150.jpg","width":200,"height":150,"filesize":8245,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309-200x150.jpg"},"full":{"file":"IMG_20240410_105309.jpg","width":2040,"height":1530,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":2316,"source_url":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-content\/uploads\/usu2509\/2024\/04\/IMG_20240410_105309.jpg","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-json\/wp\/v2\/media\/2319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolajeronidemoragas\/wp-json\/wp\/v2\/comments?post=2319"}]}}