{"id":424,"count":7,"description":"","link":"https:\/\/agora.xtec.cat\/escolaelisabadia\/tag\/taller\/","name":"taller","slug":"taller","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/tags\/424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts?tags=424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}