{"id":391,"count":1,"description":"","link":"https:\/\/agora.xtec.cat\/escolaelisabadia\/tag\/entrega-diplomes\/","name":"entrega diplomes","slug":"entrega-diplomes","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/tags\/391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts?tags=391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}