{"id":345,"count":2,"description":"","link":"https:\/\/agora.xtec.cat\/escolaelisabadia\/tag\/coneixement-del-jo\/","name":"coneixement del jo","slug":"coneixement-del-jo","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/tags\/345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts?tags=345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}