{"id":5010,"date":"2024-12-10T16:30:50","date_gmt":"2024-12-10T15:30:50","guid":{"rendered":"https:\/\/agora.xtec.cat\/escolaelisabadia\/?p=5010"},"modified":"2024-12-10T16:06:24","modified_gmt":"2024-12-10T15:06:24","slug":"infants-a-la-recerca-tardor-2024","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/escolaelisabadia\/general\/infants-a-la-recerca-tardor-2024\/","title":{"rendered":"Infants a la recerca! Tardor 2024"},"content":{"rendered":"<p>Ja estan aqu\u00ed els resultats del sorteig \u201cInfants a la recerca\u201d Etardor 2024.<\/p>\n<p>Hem rebut un munt de respostes correctes, gaireb\u00e9 150! Felicitats!<\/p>\n<div style=\"width: 1024px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-5010-1\" width=\"1024\" height=\"576\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/12\/VID_20241210_152726-1.mp4?_=1\" \/><a href=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/12\/VID_20241210_152726-1.mp4\">https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/12\/VID_20241210_152726-1.mp4<\/a><\/video><\/div>\n<p>Les persones premiades s\u00f3n:<\/p>\n<p>Bruno Ram\u00edrez P\u00e9rez, de 5\u00e8 A<\/p>\n<p>Aran Colomer Mart\u00ednez, de 5\u00e8 A<\/p>\n<p>Guillem Mart\u00ednez Gonz\u00e1lez, de 2n B<\/p>\n<p>Moltes felicitats i fins a l&#8217;any vinent!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ja estan aqu\u00ed els resultats del sorteig \u201cInfants a la recerca\u201d Etardor 2024.<br \/>\nHem rebut un munt de respostes correctes, gaireb\u00e9 150! Felicitats!<br \/>\n<a href=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/12\/VID_20241210_152726-1.mp4\">https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/12\/VID_20241210_152726-1.mp4<\/a><br \/>\nLes persones premiades s\u00f3n:<br \/>\nBruno Ram\u00edrez P\u00e9rez, de 5\u00e8 A<br \/>\nAran Colomer Mart\u00ednez, de 5\u00e8 A<br \/>\nGuillem Mart\u00ednez Gonz\u00e1lez, de 2n B<br \/>\nMoltes felicitats i fins a&hellip;  <a href=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/general\/infants-a-la-recerca-tardor-2024\/\" title=\"Read Infants a la recerca! Tardor 2024\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":6,"featured_media":706,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1,4],"tags":[346,73],"class_list":["post-5010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-portada","tag-concurs","tag-infants-a-la-recerca"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts\/5010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/comments?post=5010"}],"version-history":[{"count":1,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts\/5010\/revisions"}],"predecessor-version":[{"id":5012,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts\/5010\/revisions\/5012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/media\/706"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/media?parent=5010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/categories?post=5010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/tags?post=5010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}