{"id":3906,"date":"2024-05-22T09:42:25","date_gmt":"2024-05-22T07:42:25","guid":{"rendered":"https:\/\/agora.xtec.cat\/escolaelisabadia\/?p=3906"},"modified":"2024-05-22T09:42:25","modified_gmt":"2024-05-22T07:42:25","slug":"desafiaments-matematics-en-accio","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/escolaelisabadia\/general\/desafiaments-matematics-en-accio\/","title":{"rendered":"Desafiaments matem\u00e0tics en acci\u00f3"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">No us perdeu la nostra \u00faltima aventura matem\u00e0tica&#8230;<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> El dimecres 15 de maig els i les nostres agermanats\/es de sis\u00e8 ens van sorprendre amb una gimcana matem\u00e0tica.\u00a0<\/span><span style=\"font-weight: 400;\">Des del moment que vam arribar al pati de l\u2019escola, sab\u00edem que seria una trobada molt especial i plena de reptes!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En un primer moment, cada infant va buscar al seu agermanat o agermanada i, r\u00e0pidament, es van preparar per resoldre els enigmes. <\/span><span style=\"font-weight: 400;\">El que m\u00e9s ens va agradar va ser poder treballar conceptes matem\u00e0tics a trav\u00e9s de jocs divertits. Fins i tot aquells que ens suposaven un desafiament, es van tornar emocionants! I quan finalment vam resoldre els problemes, la sensaci\u00f3 d\u2019\u00e8xit va ser incre\u00efble.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Va ser una trobada de la qual vam gaudir molt! Gr\u00e0cies per donar-nos un dia que mai no oblidarem. Estem impacients per la pr\u00f2xima aventura matem\u00e0tica!<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3912 aligncenter\" src=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/05\/IMG_9246.jpg\" alt=\"\" width=\"500\" height=\"349\" srcset=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/05\/IMG_9246.jpg 1170w, https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/05\/IMG_9246-300x209.jpg 300w, https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/05\/IMG_9246-768x536.jpg 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3913 aligncenter\" src=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/05\/IMG_9248.jpg\" alt=\"\" width=\"500\" height=\"365\" srcset=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/05\/IMG_9248.jpg 1170w, https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/05\/IMG_9248-300x219.jpg 300w, https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/05\/IMG_9248-768x561.jpg 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3911 aligncenter\" src=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/05\/IMG_9247.jpg\" alt=\"\" width=\"500\" height=\"370\" srcset=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/05\/IMG_9247.jpg 1170w, https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/05\/IMG_9247-300x222.jpg 300w, https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2024\/05\/IMG_9247-768x568.jpg 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No us perdeu la nostra \u00faltima aventura matem\u00e0tica&#8230;<br \/>\n El dimecres 15 de maig els i les nostres agermanats\/es de sis\u00e8 ens van sorprendre amb una gimcana matem\u00e0tica.\u00a0Des del moment que vam arribar al pati de l\u2019escola, sab\u00edem que seria una trobada molt especial i plena&hellip;  <a href=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/general\/desafiaments-matematics-en-accio\/\" title=\"Read Desafiaments matem\u00e0tics en acci\u00f3\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":3910,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[11,15,1,4,5],"tags":[62,540,538,539],"class_list":["post-3906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2n","category-6e","category-general","category-portada","category-primaria","tag-agermanament","tag-convivencia","tag-learn-by-doing","tag-matematiques-vivencials"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts\/3906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/comments?post=3906"}],"version-history":[{"count":5,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts\/3906\/revisions"}],"predecessor-version":[{"id":3955,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts\/3906\/revisions\/3955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/media\/3910"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/media?parent=3906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/categories?post=3906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/tags?post=3906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}