{"id":2386,"date":"2023-11-30T12:25:36","date_gmt":"2023-11-30T11:25:36","guid":{"rendered":"https:\/\/agora.xtec.cat\/escolaelisabadia\/?p=2386"},"modified":"2023-11-27T19:26:18","modified_gmt":"2023-11-27T18:26:18","slug":"ens-digitalitzem","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/escolaelisabadia\/general\/ens-digitalitzem\/","title":{"rendered":"Ens digitalitzem!"},"content":{"rendered":"<p>Estem acabant el primer trimestre i l&#8217;alumnat de sis\u00e8 s\u00f3n molt conscients d&#8217;aquest fet.<br \/>\nAquestes setmanes estan duent a terme diferents proves per poder ser avaluats de manera objectiva. A les \u00e0rees de lleng\u00fces i matem\u00e0tiques estem fent servir el nou model que ens proposen des del Departament d&#8217;Ensenyament per dur a terme les Compet\u00e8ncies B\u00e0siques, les quals les realitzaran oficialment durant el mes d&#8217;abril. La novetat d&#8217;aquestes consta en fer servir el seu propi dispositiu inform\u00e0tic, \u00e9s a dir, el Chromebook, i llegir els enunciats i tota la informaci\u00f3 de la prova en format digital, permetent que els infants puguin ampliar les imatges o textos en les pantalles i poder localitzar les p\u00e0gines que estan treballant amb un simple moviment de dit.<\/p>\n<p>A m\u00e9s, redu\u00efm el consum de paper perqu\u00e8 cada prova consta d&#8217;aproximadament 6 fulls per infant, per tant, aquestes setmanes hem estalviat m\u00e9s de 900 fulls que equivalen al voltant de 6 arbres!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-2387\" src=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2023\/11\/IMG_20231123_122220-scaled.jpg\" alt=\"\" width=\"436\" height=\"327\" srcset=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2023\/11\/IMG_20231123_122220-scaled.jpg 2560w, https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2023\/11\/IMG_20231123_122220-300x225.jpg 300w, https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2023\/11\/IMG_20231123_122220-768x576.jpg 768w, https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2023\/11\/IMG_20231123_122220-1536x1152.jpg 1536w, https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2023\/11\/IMG_20231123_122220-2048x1536.jpg 2048w, https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2023\/11\/IMG_20231123_122220-200x150.jpg 200w\" sizes=\"auto, (max-width: 436px) 100vw, 436px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-2389\" src=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2023\/11\/IMG-20231123-WA0010.jpg\" alt=\"\" width=\"435\" height=\"580\" srcset=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2023\/11\/IMG-20231123-WA0010.jpg 1086w, https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2023\/11\/IMG-20231123-WA0010-225x300.jpg 225w, https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-content\/uploads\/usu667\/2023\/11\/IMG-20231123-WA0010-768x1024.jpg 768w\" sizes=\"auto, (max-width: 435px) 100vw, 435px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estem acabant el primer trimestre i l&#8217;alumnat de sis\u00e8 s\u00f3n molt conscients d&#8217;aquest fet.<br \/>\nAquestes setmanes estan duent a terme diferents proves per poder ser avaluats de manera objectiva. A les \u00e0rees de lleng\u00fces i matem\u00e0tiques estem fent servir el nou model que ens proposen des&hellip;  <a href=\"https:\/\/agora.xtec.cat\/escolaelisabadia\/general\/ens-digitalitzem\/\" title=\"Read Ens digitalitzem!\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":15,"featured_media":2388,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[15,1,4,5],"tags":[359,89,356,358,357,355],"class_list":["post-2386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-6e","category-general","category-portada","category-primaria","tag-chromebook","tag-cicle-superior","tag-competencies-basiques","tag-digitalitzacio","tag-proves","tag-sise"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts\/2386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/comments?post=2386"}],"version-history":[{"count":2,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts\/2386\/revisions"}],"predecessor-version":[{"id":2450,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/posts\/2386\/revisions\/2450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/media\/2388"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/media?parent=2386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/categories?post=2386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelisabadia\/wp-json\/wp\/v2\/tags?post=2386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}