{"id":1315,"date":"2019-03-06T11:43:22","date_gmt":"2019-03-06T10:43:22","guid":{"rendered":"http:\/\/agora.xtec.cat\/escolaelbruc\/?p=1315"},"modified":"2019-07-11T11:45:39","modified_gmt":"2019-07-11T09:45:39","slug":"visitem-la-biblioteca","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/escolaelbruc\/general\/visitem-la-biblioteca\/","title":{"rendered":"Visitem la biblioteca"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Els alumnes de tercer el passat dia 6 de mar\u00e7 vam fer una visita a la biblioteca del Bruc. All\u00e0 ens esperava la Maria, la nova bibliotec\u00e0ria, ens ha explicat de quins de materials disposen i com en podem fer-ne \u00fas. Tamb\u00e9 ens ha fet un recorregut per les dues sales i ens ha explicat el funcionament del pr\u00e9stec bibliotecari.<\/p>\n<p>La visita ens ha encantat!! I ens hem emportat un passaport lector com a record de la visita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<br \/>\nEls alumnes de tercer el passat dia 6 de mar\u00e7 vam fer una visita a la biblioteca del Bruc. All\u00e0 ens esperava la Maria, la nova bibliotec\u00e0ria, ens ha explicat de quins de materials disposen i com en podem fer-ne \u00fas. Tamb\u00e9 ens ha fet&hellip;  <a href=\"https:\/\/agora.xtec.cat\/escolaelbruc\/general\/visitem-la-biblioteca\/\" title=\"Read Visitem la biblioteca\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[5,1,12],"tags":[],"class_list":["post-1315","post","type-post","status-publish","format-standard","hentry","category-e-primaria","category-general","category-quart"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolaelbruc\/wp-json\/wp\/v2\/posts\/1315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolaelbruc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolaelbruc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelbruc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelbruc\/wp-json\/wp\/v2\/comments?post=1315"}],"version-history":[{"count":1,"href":"https:\/\/agora.xtec.cat\/escolaelbruc\/wp-json\/wp\/v2\/posts\/1315\/revisions"}],"predecessor-version":[{"id":1316,"href":"https:\/\/agora.xtec.cat\/escolaelbruc\/wp-json\/wp\/v2\/posts\/1315\/revisions\/1316"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/escolaelbruc\/wp-json\/wp\/v2\/media?parent=1315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelbruc\/wp-json\/wp\/v2\/categories?post=1315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolaelbruc\/wp-json\/wp\/v2\/tags?post=1315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}