{"id":2722,"date":"2020-03-21T01:51:13","date_gmt":"2020-03-21T00:51:13","guid":{"rendered":"http:\/\/agora.xtec.cat\/escolacolors\/?p=2722"},"modified":"2020-03-21T01:53:09","modified_gmt":"2020-03-21T00:53:09","slug":"cantata-de-2n","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/escolacolors\/general\/cantata-de-2n\/","title":{"rendered":"Cantata de 2n"},"content":{"rendered":"<p style=\"text-align: justify;\">Us heu assabentat de quina \u00e9s la for\u00e7a que mou l\u2019univers? Els infants de 2n ja ho saben, i per a que us ho puguin explicar, compartim les can\u00e7ons de la Cantata Municipal, per a que les pugueu escoltar a casa i les aprengueu. A m\u00e9s, tamb\u00e9 us facilitem la lletra, per a poder cantar-les totes!<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/cant.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2723\" src=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/cant.jpg\" alt=\"\" width=\"603\" height=\"341\" srcset=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/cant.jpg 603w, https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/cant-300x170.jpg 300w\" sizes=\"auto, (max-width: 603px) 100vw, 603px\" \/><\/a><a href=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/CANTATA-2n-lletra.pdf\">Lletra de les can\u00e7ons<\/a><\/p>\n<p style=\"text-align: center;\">1- Can\u00e7\u00f3 del m\u00f3n que no tenia temps<\/p>\n<!--[if lt IE 9]><script>document.createElement('audio');<\/script><![endif]-->\n<audio class=\"wp-audio-shortcode\" id=\"audio-2722-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/1.-Can\u00e7\u00f3-del-m\u00f3n-que-no-tenia-temps.mp3?_=1\" \/><a href=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/1.-Can\u00e7\u00f3-del-m\u00f3n-que-no-tenia-temps.mp3\">https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/1.-Can\u00e7\u00f3-del-m\u00f3n-que-no-tenia-temps.mp3<\/a><\/audio>\n<p style=\"text-align: center;\">2- Can\u00e7\u00f3 de la pregunta<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-2722-2\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/2.-Can\u00e7\u00f3-de-la-pregunta.mp3?_=2\" \/><a href=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/2.-Can\u00e7\u00f3-de-la-pregunta.mp3\">https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/2.-Can\u00e7\u00f3-de-la-pregunta.mp3<\/a><\/audio>\n<p style=\"text-align: center;\">3- Can\u00e7\u00f3 del m\u00f3n del foc<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-2722-3\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/3.-Can\u00e7\u00f3-del-m\u00f3n-del-foc.mp3?_=3\" \/><a href=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/3.-Can\u00e7\u00f3-del-m\u00f3n-del-foc.mp3\">https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/3.-Can\u00e7\u00f3-del-m\u00f3n-del-foc.mp3<\/a><\/audio>\n<p style=\"text-align: center;\">4- Can\u00e7\u00f3 del m\u00f3n de les muntanyes<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-2722-4\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/4.-Can\u00e7\u00f3-del-m\u00f3n-de-les-muntanyes.mp3?_=4\" \/><a href=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/4.-Can\u00e7\u00f3-del-m\u00f3n-de-les-muntanyes.mp3\">https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/4.-Can\u00e7\u00f3-del-m\u00f3n-de-les-muntanyes.mp3<\/a><\/audio>\n<p style=\"text-align: center;\">5- Can\u00e7\u00f3 del m\u00f3n dels sons<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-2722-5\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/5.-Can\u00e7\u00f3-del-m\u00f3n-dels-sons.mp3?_=5\" \/><a href=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/5.-Can\u00e7\u00f3-del-m\u00f3n-dels-sons.mp3\">https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/5.-Can\u00e7\u00f3-del-m\u00f3n-dels-sons.mp3<\/a><\/audio>\n<p style=\"text-align: center;\">6- Can\u00e7\u00f3 final<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-2722-6\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/6.-Can\u00e7\u00f3-final.mp3?_=6\" \/><a href=\"https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/6.-Can\u00e7\u00f3-final.mp3\">https:\/\/agora.xtec.cat\/escolacolors\/wp-content\/uploads\/usu1205\/2020\/03\/6.-Can\u00e7\u00f3-final.mp3<\/a><\/audio>\n","protected":false},"excerpt":{"rendered":"<p>Us heu assabentat de quina \u00e9s la for\u00e7a que mou l\u2019univers? Els infants de 2n ja ho saben, i per a que us ho puguin explicar, compartim les can\u00e7ons de la Cantata Municipal, per a que les pugueu escoltar a casa i les aprengueu. A m\u00e9s, tamb\u00e9 us facilitem la lletra, per a poder cantar-les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2723,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1,64],"tags":[368,171],"class_list":["post-2722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-mitjans","tag-cantata","tag-musica"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolacolors\/wp-json\/wp\/v2\/posts\/2722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolacolors\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolacolors\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacolors\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacolors\/wp-json\/wp\/v2\/comments?post=2722"}],"version-history":[{"count":2,"href":"https:\/\/agora.xtec.cat\/escolacolors\/wp-json\/wp\/v2\/posts\/2722\/revisions"}],"predecessor-version":[{"id":2732,"href":"https:\/\/agora.xtec.cat\/escolacolors\/wp-json\/wp\/v2\/posts\/2722\/revisions\/2732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacolors\/wp-json\/wp\/v2\/media\/2723"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/escolacolors\/wp-json\/wp\/v2\/media?parent=2722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacolors\/wp-json\/wp\/v2\/categories?post=2722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacolors\/wp-json\/wp\/v2\/tags?post=2722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}