{"id":3021,"date":"2012-11-17T00:55:53","date_gmt":"2012-11-16T23:55:53","guid":{"rendered":"http:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/11\/Sin-t\u00edtulo.png"},"modified":"2012-11-17T00:55:53","modified_gmt":"2012-11-16T23:55:53","slug":"sin-titulo-11","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/sin-titulo-11\/","title":{"rendered":"Sin t\u00edtulo"},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"class_list":["post-3021","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/11\/Sin-t\u00edtulo.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"192\" src=\"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/11\/Sin-t\u00edtulo-300x192.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/11\/Sin-t\u00edtulo-300x192.png 300w, https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/11\/Sin-t\u00edtulo.png 606w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href='https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/11\/Sin-t\u00edtulo.png'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":606,"height":388,"file":"2012\/11\/Sin-t\u00edtulo.png","sizes":{"thumbnail":{"file":"Sin-t\u00edtulo-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/11\/Sin-t\u00edtulo-150x150.png"},"medium":{"file":"Sin-t\u00edtulo-300x192.png","width":300,"height":192,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/11\/Sin-t\u00edtulo-300x192.png"},"thumb-300":{"file":"Sin-t\u00edtulo-300x250.png","width":300,"height":250,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/11\/Sin-t\u00edtulo-300x250.png"},"thumb-200":{"file":"Sin-t\u00edtulo-200x150.png","width":200,"height":150,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/11\/Sin-t\u00edtulo-200x150.png"},"full":{"file":"Sin-t\u00edtulo.png","width":606,"height":388,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/11\/Sin-t\u00edtulo.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/11\/Sin-t\u00edtulo.png","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-json\/wp\/v2\/media\/3021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-json\/wp\/v2\/comments?post=3021"}]}}