{"id":2851,"date":"2012-10-08T23:02:05","date_gmt":"2012-10-08T22:02:05","guid":{"rendered":"http:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga.jpg"},"modified":"2012-10-08T23:02:05","modified_gmt":"2012-10-08T22:02:05","slug":"ladygaga","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/ladygaga\/","title":{"rendered":"ladygaga"},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"class_list":["post-2851","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"125\" src=\"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga-300x125.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga-300x125.jpg 300w, https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga-768x319.jpg 768w, https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga.jpg 907w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href='https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga.jpg'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":907,"height":377,"file":"2012\/10\/ladygaga.jpg","sizes":{"thumbnail":{"file":"ladygaga-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga-150x150.jpg"},"medium":{"file":"ladygaga-300x125.jpg","width":300,"height":125,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga-300x125.jpg"},"medium_large":{"file":"ladygaga-768x319.jpg","width":768,"height":319,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga-768x319.jpg"},"thumb-300":{"file":"ladygaga-300x250.jpg","width":300,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga-300x250.jpg"},"thumb-200":{"file":"ladygaga-200x150.jpg","width":200,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga-200x150.jpg"},"full":{"file":"ladygaga.jpg","width":907,"height":377,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-content\/uploads\/usu1390\/2012\/10\/ladygaga.jpg","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-json\/wp\/v2\/media\/2851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacollserolacerdanyola\/wp-json\/wp\/v2\/comments?post=2851"}]}}