{"id":3487,"date":"2022-02-07T15:52:04","date_gmt":"2022-02-07T14:52:04","guid":{"rendered":"https:\/\/agora.xtec.cat\/ceipcanvidalet\/?p=3487"},"modified":"2022-02-07T15:52:40","modified_gmt":"2022-02-07T14:52:40","slug":"tallers-artistics-dia-de-la-pau","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/escolacanvidalet\/general\/tallers-artistics-dia-de-la-pau\/","title":{"rendered":"TALLERS ART\u00cdSTICS DIA DE LA PAU"},"content":{"rendered":"<p>El passat dia 31 de gener l&#8217;escola va celebrar el Dia de la Pau i de la No Viol\u00e8ncia.<\/p>\n<p>Al seg\u00fcent enlla\u00e7 trobareu un resum dels tallers art\u00edstics que es van realitzar:<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=6JE-zqq1Dk8&amp;list=PL3WxeXhWe1wYSLZSYtt-Mh_c2JMJEqpt8&amp;index=11\">TALLERS DIA DE LA PAU 2022<\/a><\/p>\n<p><a href=\"https:\/\/agora.xtec.cat\/ceipcanvidalet\/wp-content\/uploads\/usu600\/2022\/02\/26112438988_a24b9ce195.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3488\" src=\"https:\/\/agora.xtec.cat\/ceipcanvidalet\/wp-content\/uploads\/usu600\/2022\/02\/26112438988_a24b9ce195.jpg\" alt=\"\" width=\"500\" height=\"216\" srcset=\"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-content\/uploads\/usu600\/2022\/02\/26112438988_a24b9ce195.jpg 500w, https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-content\/uploads\/usu600\/2022\/02\/26112438988_a24b9ce195-300x130.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El passat dia 31 de gener l&#8217;escola va celebrar el Dia de la Pau i de la No Viol\u00e8ncia.<br \/>\nAl seg\u00fcent enlla\u00e7 trobareu un resum dels tallers art\u00edstics que es van realitzar:<br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=6JE-zqq1Dk8&amp;list=PL3WxeXhWe1wYSLZSYtt-Mh_c2JMJEqpt8&amp;index=11\">TALLERS DIA DE LA PAU 2022<\/a><br \/>\n<a href=\"https:\/\/agora.xtec.cat\/ceipcanvidalet\/wp-content\/uploads\/usu600\/2022\/02\/26112438988_a24b9ce195.jpg\"><\/a><\/p>\n","protected":false},"author":1,"featured_media":3489,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1,4],"tags":[],"class_list":["post-3487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-portada"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/posts\/3487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/comments?post=3487"}],"version-history":[{"count":1,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/posts\/3487\/revisions"}],"predecessor-version":[{"id":3490,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/posts\/3487\/revisions\/3490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/media\/3489"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/media?parent=3487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/categories?post=3487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/tags?post=3487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}