{"id":3289,"date":"2020-12-19T00:04:34","date_gmt":"2020-12-18T23:04:34","guid":{"rendered":"http:\/\/agora.xtec.cat\/ceipcanvidalet\/?p=3289"},"modified":"2020-12-19T01:27:31","modified_gmt":"2020-12-19T00:27:31","slug":"la-grossa-de-nadal-2020","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/escolacanvidalet\/general\/la-grossa-de-nadal-2020\/","title":{"rendered":"LA GROSSA DE NADAL 2020"},"content":{"rendered":"<p style=\"text-align: center;\">Benvolgudes fam\u00edlies,<\/p>\n<p style=\"text-align: center;\">hem fet el sorteig de la <strong>Grossa de Nadal<\/strong> com cada any. Aquesta vegada, ha hagut de ser d&#8217;una manera virtual que els infants no han deixat de gaudir amb la mateixa il\u00b7lusi\u00f3!<\/p>\n<p style=\"text-align: center;\">Us adjuntem el v\u00eddeo perqu\u00e8 el podeu veure!<\/p>\n<p style=\"text-align: center;\">Esperem que us agradi!<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/cifwK6l0dzY\" width=\"400\" height=\"315\" frameborder=\"0\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Benvolgudes fam\u00edlies,<br \/>\nhem fet el sorteig de la Grossa de Nadal com cada any. Aquesta vegada, ha hagut de ser d&#8217;una manera virtual que els infants no han deixat de gaudir amb la mateixa il\u00b7lusi\u00f3!<br \/>\nUs adjuntem el v\u00eddeo perqu\u00e8 el podeu veure!<br \/>\nEsperem que us agradi!<br \/>\n\ufeff<\/p>\n","protected":false},"author":24,"featured_media":3290,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1,4],"tags":[],"class_list":["post-3289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-portada"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/posts\/3289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/comments?post=3289"}],"version-history":[{"count":2,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/posts\/3289\/revisions"}],"predecessor-version":[{"id":3292,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/posts\/3289\/revisions\/3292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/media\/3290"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/media?parent=3289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/categories?post=3289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/tags?post=3289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}