{"id":1307,"date":"2017-05-09T13:10:05","date_gmt":"2017-05-09T11:10:05","guid":{"rendered":"http:\/\/agora.xtec.cat\/ceipcanvidalet\/?p=1307"},"modified":"2017-05-09T13:10:05","modified_gmt":"2017-05-09T11:10:05","slug":"ordres-boges-carnestoltes-2n","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/escolacanvidalet\/primaria\/1r\/ordres-boges-carnestoltes-2n\/","title":{"rendered":"ORDRES BOGES CARNESTOLTES 2N"},"content":{"rendered":"<h6>Els de 2n som molt complidors.<\/h6>\n<h6>Aqu\u00ed ens teniu respectant les ordres boges del Carnestoltes!<\/h6>\n<p><a href=\"https:\/\/goo.gl\/photos\/KS36FGj8sttafvm56\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1308 size-full\" src=\"http:\/\/agora.xtec.cat\/ceipcanvidalet\/wp-content\/uploads\/usu600\/2017\/05\/resized_SANY0163.jpg\" alt=\"resized_SANY0163\" width=\"324\" height=\"247\" srcset=\"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-content\/uploads\/usu600\/2017\/05\/resized_SANY0163.jpg 324w, https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-content\/uploads\/usu600\/2017\/05\/resized_SANY0163-300x229.jpg 300w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Els de 2n som molt complidors.<br \/>\nAqu\u00ed ens teniu respectant les ordres boges del Carnestoltes!<br \/>\n<a href=\"https:\/\/goo.gl\/photos\/KS36FGj8sttafvm56\" target=\"_blank\"><\/a><\/p>\n","protected":false},"author":1,"featured_media":1308,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[10,11],"tags":[24,39],"class_list":["post-1307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1r","category-httpcanvidaletcicleinicial-blogspot-com-es","tag-festes","tag-primaria"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/posts\/1307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/comments?post=1307"}],"version-history":[{"count":1,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/posts\/1307\/revisions"}],"predecessor-version":[{"id":1309,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/posts\/1307\/revisions\/1309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/media\/1308"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/media?parent=1307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/categories?post=1307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/tags?post=1307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}