{"id":14,"count":40,"description":"<a href=\"http:\/\/canvidaletciclesuperior.blogspot.com.es\/\" target=\"_blank\"><img class=\"alignnone size-full wp-image-248\" src=\"http:\/\/agora.xtec.cat\/ceipcanvidalet\/wp-content\/uploads\/usu600\/2015\/11\/BLOGsuperior.jpg\" alt=\"BLOGsuperior\" width=\"626\" height=\"279\" \/><\/a>","link":"https:\/\/agora.xtec.cat\/escolacanvidalet\/categoria\/primaria\/httpcanvidaletciclesuperior-blogspot-com-es\/","name":"5\u00e8","slug":"httpcanvidaletciclesuperior-blogspot-com-es","taxonomy":"category","parent":5,"meta":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/categories\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/categories\/5"}],"wp:post_type":[{"href":"https:\/\/agora.xtec.cat\/escolacanvidalet\/wp-json\/wp\/v2\/posts?categories=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}