{"id":5874,"date":"2025-05-13T16:18:29","date_gmt":"2025-05-13T14:18:29","guid":{"rendered":"https:\/\/agora.xtec.cat\/esclagranadella\/?p=5874"},"modified":"2025-05-13T16:18:29","modified_gmt":"2025-05-13T14:18:29","slug":"sortida-esportiva-2","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/esclagranadella\/portada\/sortida-esportiva-2\/","title":{"rendered":"Sortida Esportiva"},"content":{"rendered":"<p style=\"margin-right: 7.35pt;text-align: justify;line-height: 150%;background: white\"><span style=\"font-family: 'Calibri',sans-serif;color: black\">L&#8217;alumnat de la ZER Elaia de cicle mitj\u00e0 va tenir l&#8217;oportunitat de participar a la recent jornada esportiva de la comarca, una experi\u00e8ncia molt enriquidora i divertida per tots i totes. Durant l&#8217;activitat, els nens i nenes van gaudir de diferents disciplines d&#8217;atletisme, com curses, salts i llan\u00e7aments, que els van permetre posar a prova les seves habilitats i passar una estona activa i saludable. Aquesta jornada va ser una gran ocasi\u00f3 perqu\u00e8 l\u2019alumnat compart\u00eds moments de diversi\u00f3, aprenentatge i conviv\u00e8ncia, refor\u00e7ant els valors de l&#8217;esport i la import\u00e0ncia de mantenir-se actius. Sense dubte, una experi\u00e8ncia que recordaran amb il\u00b7lusi\u00f3!<\/span><\/p>\n<p>&nbsp;<\/p>\n\r\n\t<div class=\"slideshow_container slideshow_container_style-light\" style=\"height: 300px; \" data-slideshow-id=\"5887\" data-style-name=\"style-light\" data-style-version=\"2.3.1\" >\r\n\r\n\t\t\t\t\t<div class=\"slideshow_loading_icon\"><\/div>\r\n\t\t\r\n\t\t<div class=\"slideshow_content\" style=\"display: none;\">\r\n\r\n\t\t\t<div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2025\/05\/31700541-7d48-4255-8265-f0b115fda271-1.jpg\" alt=\"31700541-7d48-4255-8265-f0b115fda271 (1)\" width=\"1040\" height=\"780\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">31700541-7d48-4255-8265-f0b115fda271 (1)<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2025\/05\/IMG20250506102105-1.jpg\" alt=\"IMG20250506102105 (1)\" width=\"2080\" height=\"936\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG20250506102105 (1)<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2025\/05\/IMG20250506102838-1.jpg\" alt=\"IMG20250506102838 (1)\" width=\"2080\" height=\"936\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG20250506102838 (1)<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2025\/05\/IMG20250506102956-2.jpg\" alt=\"IMG20250506102956 (2)\" width=\"2080\" height=\"936\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG20250506102956 (2)<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2025\/05\/IMG20250506102956-1.jpg\" alt=\"IMG20250506102956 (1)\" width=\"2080\" height=\"936\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG20250506102956 (1)<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2025\/05\/IMG20250506110745-1.jpg\" alt=\"IMG20250506110745 (1)\" width=\"936\" height=\"2080\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG20250506110745 (1)<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2025\/05\/IMG20250506111639-1.jpg\" alt=\"IMG20250506111639 (1)\" width=\"2000\" height=\"900\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG20250506111639 (1)<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2025\/05\/IMG20250506111904-1.jpg\" alt=\"IMG20250506111904 (1)\" width=\"2000\" height=\"900\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG20250506111904 (1)<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2025\/05\/IMG20250506121205-1.jpg\" alt=\"IMG20250506121205 (1)\" width=\"2000\" height=\"900\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG20250506121205 (1)<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2025\/05\/IMG20250506134727-1.jpg\" alt=\"IMG20250506134727 (1)\" width=\"2000\" height=\"900\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG20250506134727 (1)<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2025\/05\/IMG_3959-1.jpg\" alt=\"IMG_3959 (1)\" width=\"756\" height=\"1008\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3959 (1)<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"slideshow_controlPanel slideshow_transparent\" style=\"display: none;\"><ul><li class=\"slideshow_togglePlay\" data-play-text=\"Visualitza\" data-pause-text=\"Pausa\"><\/li><\/ul><\/div>\r\n\r\n\t\t<div class=\"slideshow_button slideshow_previous slideshow_transparent\" role=\"button\" data-previous-text=\"Anterior\" style=\"display: none;\"><\/div>\r\n\t\t<div class=\"slideshow_button slideshow_next slideshow_transparent\" role=\"button\" data-next-text=\"Seg\u00fcent\" style=\"display: none;\"><\/div>\r\n\r\n\t\t<div class=\"slideshow_pagination\" style=\"display: none;\" data-go-to-text=\"V\u00e9s a la diapositiva\"><div class=\"slideshow_pagination_center\"><\/div><\/div>\r\n\r\n\t\t<!-- WordPress Slideshow Version 2.3.1 -->\r\n\r\n\t\t\t<\/div>\r\n\r\n\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;alumnat de la ZER Elaia de cicle mitj\u00e0 va tenir l&#8217;oportunitat de participar a la recent jornada esportiva de la comarca, una experi\u00e8ncia molt enriquidora i divertida per tots i totes. Durant l&#8217;activitat, els nens i nenes van gaudir de diferents disciplines d&#8217;atletisme, com curses, salts i llan\u00e7aments, que els van permetre posar a prova [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":5875,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4,31],"tags":[],"class_list":["post-5874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada","category-sortides"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/posts\/5874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/comments?post=5874"}],"version-history":[{"count":2,"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/posts\/5874\/revisions"}],"predecessor-version":[{"id":5888,"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/posts\/5874\/revisions\/5888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/media\/5875"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/media?parent=5874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/categories?post=5874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/tags?post=5874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}