{"id":508,"date":"2015-11-27T19:34:50","date_gmt":"2015-11-27T18:34:50","guid":{"rendered":"http:\/\/agora.xtec.cat\/esclagranadella\/?p=508"},"modified":"2015-11-27T19:37:50","modified_gmt":"2015-11-27T18:37:50","slug":"sortida-caixaforum","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/esclagranadella\/portada\/sortida-caixaforum\/","title":{"rendered":"Sortida: CaixaForum"},"content":{"rendered":"<p>Els alumnes de Cicle Mitj\u00e0 i Superior han \u00a0visitat \u00a0 l&#8217;exposici\u00f3 &#8220;SOROLLA : APUNTS A LA SORRA&#8221;.<\/p>\n\r\n\t<div class=\"slideshow_container slideshow_container_style-light\" style=\" \" data-slideshow-id=\"510\" data-style-name=\"style-light\" data-style-version=\"2.3.1\" >\r\n\r\n\t\t\t\t\t<div class=\"slideshow_loading_icon\"><\/div>\r\n\t\t\r\n\t\t<div class=\"slideshow_content\" style=\"display: none;\">\r\n\r\n\t\t\t<div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/IMG_3437.jpg\" alt=\"IMG_3437\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3437<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/IMG_3436.jpg\" alt=\"IMG_3436\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3436<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/IMG_3434.jpg\" alt=\"IMG_3434\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3434<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/IMG_3433.jpg\" alt=\"IMG_3433\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3433<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/IMG_3432.jpg\" alt=\"IMG_3432\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3432<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/IMG_3431.jpg\" alt=\"IMG_3431\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3431<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/IMG_3430.jpg\" alt=\"IMG_3430\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3430<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/IMG_3429.jpg\" alt=\"IMG_3429\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3429<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/IMG_3428.jpg\" alt=\"IMG_3428\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3428<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/IMG_3426.jpg\" alt=\"IMG_3426\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3426<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/IMG_3422.jpg\" alt=\"IMG_3422\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3422<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/IMG_3421.jpg\" alt=\"IMG_3421\" width=\"800\" height=\"600\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">IMG_3421<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/20151127_123645.jpg\" alt=\"20151127_123645\" width=\"800\" height=\"450\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">20151127_123645<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/20151127_122430.jpg\" alt=\"20151127_122430\" width=\"800\" height=\"450\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">20151127_122430<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/20151127_122358.jpg\" alt=\"20151127_122358\" width=\"800\" height=\"450\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">20151127_122358<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/20151127_122346.jpg\" alt=\"20151127_122346\" width=\"800\" height=\"450\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">20151127_122346<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/20151127_122327.jpg\" alt=\"20151127_122327\" width=\"800\" height=\"450\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">20151127_122327<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/20151127_121359.jpg\" alt=\"20151127_121359\" width=\"800\" height=\"450\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">20151127_121359<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/20151127_121250.jpg\" alt=\"20151127_121250\" width=\"800\" height=\"450\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">20151127_121250<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/esclagranadella\/wp-content\/uploads\/usu409\/2015\/11\/20151127_113251.jpg\" alt=\"20151127_113251\" width=\"800\" height=\"450\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">20151127_113251<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"slideshow_controlPanel slideshow_transparent\" style=\"display: none;\"><ul><li class=\"slideshow_togglePlay\" data-play-text=\"Visualitza\" data-pause-text=\"Pausa\"><\/li><\/ul><\/div>\r\n\r\n\t\t<div class=\"slideshow_button slideshow_previous slideshow_transparent\" role=\"button\" data-previous-text=\"Anterior\" style=\"display: none;\"><\/div>\r\n\t\t<div class=\"slideshow_button slideshow_next slideshow_transparent\" role=\"button\" data-next-text=\"Seg\u00fcent\" style=\"display: none;\"><\/div>\r\n\r\n\t\t<div class=\"slideshow_pagination\" style=\"display: none;\" data-go-to-text=\"V\u00e9s a la diapositiva\"><div class=\"slideshow_pagination_center\"><\/div><\/div>\r\n\r\n\t\t<!-- WordPress Slideshow Version 2.3.1 -->\r\n\r\n\t\t\t<\/div>\r\n\r\n\n","protected":false},"excerpt":{"rendered":"<p>Els alumnes de Cicle Mitj\u00e0 i Superior han \u00a0visitat \u00a0 l&#8217;exposici\u00f3 &#8220;SOROLLA : APUNTS A LA SORRA&#8221;.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[26,4,31],"tags":[],"class_list":["post-508","post","type-post","status-publish","format-standard","hentry","category-fotografies","category-portada","category-sortides"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/posts\/508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/comments?post=508"}],"version-history":[{"count":3,"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/posts\/508\/revisions"}],"predecessor-version":[{"id":532,"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/posts\/508\/revisions\/532"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/media?parent=508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/categories?post=508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/esclagranadella\/wp-json\/wp\/v2\/tags?post=508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}