{"id":8086,"date":"2023-11-27T10:24:38","date_gmt":"2023-11-27T09:24:38","guid":{"rendered":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb.jpg"},"modified":"2023-11-27T10:24:38","modified_gmt":"2023-11-27T09:24:38","slug":"f39522fa-7ba5-4bee-88ca-d755ec7b32eb","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/general\/el-dia-de-la-ciencia-va-ser-un-exit\/attachment\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb\/","title":{"rendered":"f39522fa-7ba5-4bee-88ca-d755ec7b32eb"},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"class_list":["post-8086","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb-225x300.jpg 225w, https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb-768x1024.jpg 768w, https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb-1152x1536.jpg 1152w, https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb.jpg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":1600,"file":"2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb.jpg","sizes":{"medium":{"file":"f39522fa-7ba5-4bee-88ca-d755ec7b32eb-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb-225x300.jpg"},"large":{"file":"f39522fa-7ba5-4bee-88ca-d755ec7b32eb-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb-768x1024.jpg"},"thumbnail":{"file":"f39522fa-7ba5-4bee-88ca-d755ec7b32eb-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb-150x150.jpg"},"medium_large":{"file":"f39522fa-7ba5-4bee-88ca-d755ec7b32eb-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb-768x1024.jpg"},"1536x1536":{"file":"f39522fa-7ba5-4bee-88ca-d755ec7b32eb-1152x1536.jpg","width":1152,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb-1152x1536.jpg"},"thumb-300":{"file":"f39522fa-7ba5-4bee-88ca-d755ec7b32eb-300x250.jpg","width":300,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb-300x250.jpg"},"thumb-200":{"file":"f39522fa-7ba5-4bee-88ca-d755ec7b32eb-200x150.jpg","width":200,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb-200x150.jpg"},"full":{"file":"f39522fa-7ba5-4bee-88ca-d755ec7b32eb.jpg","width":1200,"height":1600,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"1700843283","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":7986,"source_url":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-content\/uploads\/usu1046\/2023\/11\/f39522fa-7ba5-4bee-88ca-d755ec7b32eb.jpg","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-json\/wp\/v2\/media\/8086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/esc-leseresdecreixell\/wp-json\/wp\/v2\/comments?post=8086"}]}}