{"id":2296,"date":"2026-04-08T15:32:29","date_gmt":"2026-04-08T13:32:29","guid":{"rendered":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/?p=2296"},"modified":"2026-04-09T02:37:23","modified_gmt":"2026-04-09T00:37:23","slug":"preinscripcio-del-curs-2026-2027-del-19-al-29-de-juny","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/general\/preinscripcio-del-curs-2026-2027-del-19-al-29-de-juny\/","title":{"rendered":"Preinscripci\u00f3 del curs 2026-2027: del 19 al 29 de juny"},"content":{"rendered":"<p><a href=\"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/general\/preinscripcio-del-curs-2026-2027-del-19-al-29-de-juny\/attachment\/preinscripcio-2026-27-1200-x-630-px-1\/\" rel=\"attachment wp-att-2301\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2312 size-medium\" src=\"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-content\/uploads\/usu1596\/2026\/04\/Preinscripcio-2026-27-1200-x-630-px-1-300x158.jpg\" alt=\"\" width=\"300\" height=\"158\" srcset=\"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-content\/uploads\/usu1596\/2026\/04\/Preinscripcio-2026-27-1200-x-630-px-1-300x158.jpg 300w, https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-content\/uploads\/usu1596\/2026\/04\/Preinscripcio-2026-27-1200-x-630-px-1-1024x538.jpg 1024w, https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-content\/uploads\/usu1596\/2026\/04\/Preinscripcio-2026-27-1200-x-630-px-1-768x403.jpg 768w, https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-content\/uploads\/usu1596\/2026\/04\/Preinscripcio-2026-27-1200-x-630-px-1.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/general\/preinscripcio-del-curs-2026-2027-del-19-al-29-de-juny\/attachment\/preinscripcio-2026-27-1200-x-630-px-1\/\" rel=\"attachment wp-att-2301\"><\/a><\/p>\n","protected":false},"author":1,"featured_media":2313,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/posts\/2296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/comments?post=2296"}],"version-history":[{"count":5,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/posts\/2296\/revisions"}],"predecessor-version":[{"id":2314,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/posts\/2296\/revisions\/2314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/media\/2313"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/media?parent=2296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/categories?post=2296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/tags?post=2296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}