{"id":1474,"date":"2023-03-09T17:18:00","date_gmt":"2023-03-09T16:18:00","guid":{"rendered":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/?p=1474"},"modified":"2025-09-16T13:35:55","modified_gmt":"2025-09-16T11:35:55","slug":"felic-dia-de-la-dona","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/general\/felic-dia-de-la-dona\/","title":{"rendered":"Feli\u00e7 dia de la Dona"},"content":{"rendered":"<p><a href=\"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-content\/uploads\/usu1596\/2023\/03\/8m6penja.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1460\" src=\"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-content\/uploads\/usu1596\/2023\/03\/8m6penja.jpg\" alt=\"\" width=\"1000\" height=\"280\" srcset=\"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-content\/uploads\/usu1596\/2023\/03\/8m6penja.jpg 1000w, https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-content\/uploads\/usu1596\/2023\/03\/8m6penja-300x84.jpg 300w, https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-content\/uploads\/usu1596\/2023\/03\/8m6penja-768x215.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>Feli\u00e7 dia de la dona!<\/p>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-content\/uploads\/usu1596\/2023\/03\/8m6penja.jpg\"><\/a><br \/>\nFeli\u00e7 dia de la dona!<\/p>\n","protected":false},"author":1,"featured_media":1460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/posts\/1474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/comments?post=1474"}],"version-history":[{"count":3,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/posts\/1474\/revisions"}],"predecessor-version":[{"id":1477,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/posts\/1474\/revisions\/1477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/media\/1460"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/media?parent=1474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/categories?post=1474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/cfasantrocbadalona\/wp-json\/wp\/v2\/tags?post=1474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}