{"id":12124,"date":"2024-02-06T11:37:18","date_gmt":"2024-02-06T10:37:18","guid":{"rendered":"https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-content\/uploads\/usu2187\/2024\/02\/xerrades-families.png"},"modified":"2024-02-06T11:37:18","modified_gmt":"2024-02-06T10:37:18","slug":"xerrades-families","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/ceipsantjosep\/xerrades-families\/","title":{"rendered":"xerrades families"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"class_list":["post-12124","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-content\/uploads\/usu2187\/2024\/02\/xerrades-families.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-content\/uploads\/usu2187\/2024\/02\/xerrades-families.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-content\/uploads\/usu2187\/2024\/02\/xerrades-families.png 300w, https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-content\/uploads\/usu2187\/2024\/02\/xerrades-families-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href='https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-content\/uploads\/usu2187\/2024\/02\/xerrades-families.png'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":300,"height":300,"file":"2024\/02\/xerrades-families.png","filesize":174303,"sizes":{"thumbnail":{"file":"xerrades-families-150x150.png","width":150,"height":150,"filesize":41509,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-content\/uploads\/usu2187\/2024\/02\/xerrades-families-150x150.png"},"thumb-300":{"file":"xerrades-families-300x250.png","width":300,"height":250,"filesize":132173,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-content\/uploads\/usu2187\/2024\/02\/xerrades-families-300x250.png"},"thumb-200":{"file":"xerrades-families-200x150.png","width":200,"height":150,"filesize":54318,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-content\/uploads\/usu2187\/2024\/02\/xerrades-families-200x150.png"},"full":{"file":"xerrades-families.png","width":300,"height":300,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-content\/uploads\/usu2187\/2024\/02\/xerrades-families.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-content\/uploads\/usu2187\/2024\/02\/xerrades-families.png","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-json\/wp\/v2\/media\/12124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceipsantjosep\/wp-json\/wp\/v2\/comments?post=12124"}]}}