{"id":9,"name":"Mireia Garrido","url":"","description":"","link":"https:\/\/agora.xtec.cat\/ceippereviver\/author\/mireiagarrido\/","slug":"mireiagarrido","avatar_urls":{"24":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/plugins\/buddypress\/bp-core\/images\/mystery-man-50.jpg","48":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/plugins\/buddypress\/bp-core\/images\/mystery-man-50.jpg","96":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/plugins\/buddypress\/bp-core\/images\/mystery-man.jpg"},"meta":{"getwid_ai_accept_terms":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_last_posted":0},"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/users\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/users"}]}}