{"id":111,"count":1,"description":"","link":"https:\/\/agora.xtec.cat\/ceippereviver\/tag\/cala-montjoi\/","name":"cala montjoi","slug":"cala-montjoi","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/tags\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts?tags=111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}