{"id":897,"date":"2017-01-24T17:34:17","date_gmt":"2017-01-24T16:34:17","guid":{"rendered":"http:\/\/agora.xtec.cat\/ceippereviver\/?p=897"},"modified":"2017-01-24T17:34:17","modified_gmt":"2017-01-24T16:34:17","slug":"el-patge-va-visitar-p4a","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/ceippereviver\/i3-i4-i5\/el-patge-va-visitar-p4a\/","title":{"rendered":"El patge va visitar P4A"},"content":{"rendered":"<p>Abans de les vacances de Nadal, va venir el patge reial a buscar les cartes dels nens de l&#8217;escola.<\/p>\n<p>Els nens i nenes de la classe dels taurons vam demanar moltes coses i quan vam tornar de les vacances, vam trobar uns regals a la classe.<\/p>\n<p>Per problemes inform\u00e0tics, no vam poder penjar aquestes fotos abans, per\u00f2 finalment les teniu aqu\u00ed!<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/goo.gl\/photos\/1VTw4MTDH34SnfgBA\" target=\"_blank\">\u00c0lbum<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abans de les vacances de Nadal, va venir el patge reial a buscar les cartes dels nens de l&#8217;escola.<br \/>\nEls nens i nenes de la classe dels taurons vam demanar moltes coses i quan vam tornar de les vacances, vam trobar uns regals a la classe.<br \/>\nPer&hellip;  <a href=\"https:\/\/agora.xtec.cat\/ceippereviver\/i3-i4-i5\/el-patge-va-visitar-p4a\/\" title=\"Read El patge va visitar P4A\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":9,"featured_media":696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[67,2,62,4],"tags":[],"class_list":["post-897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curs-2016-2017","category-i3-i4-i5","category-nascuts-2012","category-portada"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/comments?post=897"}],"version-history":[{"count":1,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/897\/revisions"}],"predecessor-version":[{"id":898,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/897\/revisions\/898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/media\/696"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/media?parent=897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/categories?post=897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/tags?post=897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}