{"id":6476,"date":"2025-02-11T13:53:25","date_gmt":"2025-02-11T12:53:25","guid":{"rendered":"https:\/\/agora.xtec.cat\/ceippereviver\/?p=6476"},"modified":"2025-02-11T13:53:25","modified_gmt":"2025-02-11T12:53:25","slug":"4t-mobilitat-segura","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/ceippereviver\/general\/4t-mobilitat-segura\/","title":{"rendered":"4t MOBILITAT SEGURA"},"content":{"rendered":"<p>Els i les alumnes de 4t de prim\u00e0ria han realitzat un taller sobre mobilitat segura organitzat per la Policia Municipal de Terrassa. Han identificat els conceptes de seguretat i perill en relaci\u00f3 amb els diferents espais de mobilitat de l&#8217;entorn, han percebut <span style=\"font-family: inherit; font-size: 1em;\">els elements de la mobilitat que comporten un risc, i han r<\/span><span style=\"font-family: inherit; font-size: 1em;\">eflexionat sobre els despla\u00e7aments segurs i <\/span><span style=\"font-family: inherit; font-size: 1em;\">el perqu\u00e8 de les nostres conductes segures o de risc.<\/span><\/p>\n<p><a href=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8032-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-6477\" src=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8032-768x1024.jpeg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8032-768x1024.jpeg 768w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8032-225x300.jpeg 225w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8032-1152x1536.jpeg 1152w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8032-1536x2048.jpeg 1536w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8032-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a> <a href=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8029-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-6478\" src=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8029-768x1024.jpeg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8029-768x1024.jpeg 768w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8029-225x300.jpeg 225w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8029-1152x1536.jpeg 1152w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8029-1536x2048.jpeg 1536w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8029-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a> <a href=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8025-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-6479\" src=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8025-768x1024.jpeg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8025-768x1024.jpeg 768w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8025-225x300.jpeg 225w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8025-1152x1536.jpeg 1152w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8025-1536x2048.jpeg 1536w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8025-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a> <a href=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8031-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-6480\" src=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8031-1024x768.jpeg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8031-1024x768.jpeg 1024w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8031-300x225.jpeg 300w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8031-768x576.jpeg 768w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8031-1536x1152.jpeg 1536w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8031-2048x1536.jpeg 2048w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8031-200x150.jpeg 200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a> <a href=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8028-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-6481\" src=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8028-1024x768.jpeg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8028-1024x768.jpeg 1024w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8028-300x225.jpeg 300w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8028-768x576.jpeg 768w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8028-1536x1152.jpeg 1536w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8028-2048x1536.jpeg 2048w, https:\/\/agora.xtec.cat\/ceippereviver\/wp-content\/uploads\/usu879\/2025\/02\/IMG_8028-200x150.jpeg 200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Els i les alumnes de 4t de prim\u00e0ria han realitzat un taller sobre mobilitat segura organitzat per la Policia Municipal de Terrassa. Han identificat els conceptes de seguretat i perill en relaci\u00f3 amb els diferents espais de mobilitat de l&#8217;entorn, han percebut els elements de&hellip;  <a href=\"https:\/\/agora.xtec.cat\/ceippereviver\/general\/4t-mobilitat-segura\/\" title=\"Read 4t MOBILITAT SEGURA\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":60,"featured_media":6477,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[71,189,1,4],"tags":[],"class_list":["post-6476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cicle-mitja","category-curs-2024-2025","category-general","category-portada"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/6476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/comments?post=6476"}],"version-history":[{"count":1,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/6476\/revisions"}],"predecessor-version":[{"id":6482,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/6476\/revisions\/6482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/media\/6477"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/media?parent=6476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/categories?post=6476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/tags?post=6476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}