{"id":5703,"date":"2023-02-06T19:01:02","date_gmt":"2023-02-06T18:01:02","guid":{"rendered":"https:\/\/agora.xtec.cat\/ceippereviver\/?p=5703"},"modified":"2023-02-06T19:01:02","modified_gmt":"2023-02-06T18:01:02","slug":"activem-lanella-verda-de-terrassa","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/ceippereviver\/general\/activem-lanella-verda-de-terrassa\/","title":{"rendered":"Activem l&#8217;Anella Verda de Terrassa"},"content":{"rendered":"<p>Avui hem tingut la oportunitat de formar part d&#8217;un projecte que est\u00e0 realitzant l&#8217;alumnat de segon del CFGM de Guia en el Medi Natural i Temps de Lleure a l&#8217;IES Santa Eul\u00e0lia i que han anomenat &#8220;L\u2019ANELLA VERDA&#8221;, amb tot un seguit de propostes i activitats de les que han pogut gaudir alguns dels nostres infants.<\/p>\n<p>Hem realitzat el taller &#8220;ecoruta&#8221; i &#8220;estacions ambientals&#8221; on hem pogut descobrir i valorar l&#8217;\u00fas i aprofitament de diversos materials, aprendre diverses t\u00e8cniques i recursos del reciclatge aix\u00ed com iniciar-nos en h\u00e0bits d&#8217;ordre, neteja i respecte pel medi ambient. A m\u00e9s a m\u00e9s, ens hem divertit molt a trav\u00e9s dels jocs i hem gaudit d&#8217;un mat\u00ed en plena natura.<\/p>\n<p>Moltes gr\u00e0cies a la comunitat del IES Santa Eul\u00e0lia per haver-nos convidat a formar part d&#8217;aquest projecte tant interessant!!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avui hem tingut la oportunitat de formar part d&#8217;un projecte que est\u00e0 realitzant l&#8217;alumnat de segon del CFGM de Guia en el Medi Natural i Temps de Lleure a l&#8217;IES Santa Eul\u00e0lia i que han anomenat &#8220;L\u2019ANELLA VERDA&#8221;, amb tot un seguit de propostes i&hellip;  <a href=\"https:\/\/agora.xtec.cat\/ceippereviver\/general\/activem-lanella-verda-de-terrassa\/\" title=\"Read Activem l&#8217;Anella Verda de Terrassa\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":32,"featured_media":5705,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[172,1,4,5],"tags":[],"class_list":["post-5703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curs-2022-2023","category-general","category-portada","category-primaria"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/5703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/comments?post=5703"}],"version-history":[{"count":2,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/5703\/revisions"}],"predecessor-version":[{"id":5706,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/5703\/revisions\/5706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/media\/5705"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/media?parent=5703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/categories?post=5703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/tags?post=5703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}