{"id":5201,"date":"2021-10-22T12:36:53","date_gmt":"2021-10-22T10:36:53","guid":{"rendered":"https:\/\/agora.xtec.cat\/ceippereviver\/?p=5201"},"modified":"2021-10-26T10:06:00","modified_gmt":"2021-10-26T08:06:00","slug":"decorem-les-portes-de-cicle-inicial","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/ceippereviver\/general\/decorem-les-portes-de-cicle-inicial\/","title":{"rendered":"Decorem les portes de cicle inicial"},"content":{"rendered":"<p>Tenim el plaer de presentar-vos les portes de les aules de Cicle Inicial!<\/p>\n<p>En realitat, el que veieu, s\u00f3n els productes finals d&#8217;uns projectes sobre el nom de la classe que hem estat fent durant aquestes primeres setmanes amb la intenci\u00f3 de crear cohesi\u00f3 i pertinen\u00e7a de grup. Cada classe escull el nom que vol tenir per aquest curs i, amb la intenci\u00f3 de comunicar-ho a la resta de l&#8217;escola, es proposa fer un disseny per la porta d&#8217;entrada a les aules. Per arribar a aquest producte final els nens i nenes investiguen, experimenten, busquen informaci\u00f3, creen, dissenyen, aprenen a relacionar-se amb els altres, exposen a la resta dels companys\/es,&#8230; fent una feina excel\u00b7lent en els diversos \u00e0mbits de coneixement.<\/p>\n<p>En aquest <a href=\"https:\/\/photos.app.goo.gl\/Bq6tvCiux3Unutww5\">\u00e0lbum<\/a> teniu els nostres productes finals dels projectes:<\/p>\n<p><a href=\"https:\/\/photos.app.goo.gl\/Keo11vpGYV1AVya16\">1r A: Les m\u00f2mies<\/a><\/p>\n<p><a href=\"https:\/\/photos.app.goo.gl\/mHaq3W2L8JhpBML57\">1r B: L&#8217;arc de Sant Mart\u00ed<\/a><\/p>\n<p><a href=\"https:\/\/photos.app.goo.gl\/J4v97qqmjA4tCAXw9\">2n A: Els ping\u00fcins<\/a><\/p>\n<p><a href=\"https:\/\/photos.app.goo.gl\/PGnzthfBMTViRqYh7\">2n B: Els pintors i les pintores<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tenim el plaer de presentar-vos les portes de les aules de Cicle Inicial!<br \/>\nEn realitat, el que veieu, s\u00f3n els productes finals d&#8217;uns projectes sobre el nom de la classe que hem estat fent durant aquestes primeres setmanes amb la intenci\u00f3 de crear cohesi\u00f3 i pertinen\u00e7a&hellip;  <a href=\"https:\/\/agora.xtec.cat\/ceippereviver\/general\/decorem-les-portes-de-cicle-inicial\/\" title=\"Read Decorem les portes de cicle inicial\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":32,"featured_media":5202,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[10,84,1,4,78],"tags":[],"class_list":["post-5201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1r-i-2n","category-cicle-inicial","category-general","category-portada","category-projectes"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/5201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/comments?post=5201"}],"version-history":[{"count":2,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/5201\/revisions"}],"predecessor-version":[{"id":5218,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/5201\/revisions\/5218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/media\/5202"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/media?parent=5201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/categories?post=5201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/tags?post=5201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}