{"id":3579,"date":"2019-05-11T18:02:19","date_gmt":"2019-05-11T16:02:19","guid":{"rendered":"http:\/\/agora.xtec.cat\/ceippereviver\/?p=3579"},"modified":"2019-05-11T18:02:19","modified_gmt":"2019-05-11T16:02:19","slug":"p-4-b-treballem-miro","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/ceippereviver\/i3-i4-i5\/p-4-b-treballem-miro\/","title":{"rendered":"P-4 B TREBALLEM MIRO"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/photos.app.goo.gl\/rEAxkh1khuFRNgdZ9\">ALBUM P-4 B<\/a><\/p>\n<p>Aquesta setmana han vingut a l\u2019escola a fer-nos un taller de Joan Mir\u00f3. Aquest, \u00e9s un pintor que tot just comencem a con\u00e8ixer i que ens acompanyar\u00e0 durant aquest tercer trimestre.<\/p>\n<p>El taller ha estat for\u00e7a divertit i hem apr\u00e8s moltes coses sobre la vida d\u2019en Joan Mir\u00f3, els elements que pintava, el significat d\u2019algun dels seus quadres i les t\u00e8cniques que feia servir.<\/p>\n<p>A partir d\u2019ara, i durant aquests dies, provarem diferents t\u00e8cniques pl\u00e0stiques que ens acostaran una mica m\u00e9s a les obres d\u2019aquest gran pintor.<\/p>\n<p>La feina finalitzar\u00e0 amb la visita al museu de Barcelona que exposa els seus quadres: LA FUNDACI\u00d3 MIR\u00d3<\/p>\n<p>Esperem que gaudiu tant com nosaltres!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<br \/>\n<a href=\"https:\/\/photos.app.goo.gl\/rEAxkh1khuFRNgdZ9\">ALBUM P-4 B<\/a><br \/>\nAquesta setmana han vingut a l\u2019escola a fer-nos un taller de Joan Mir\u00f3. Aquest, \u00e9s un pintor que tot just comencem a con\u00e8ixer i que ens acompanyar\u00e0 durant aquest tercer trimestre.<br \/>\nEl taller ha estat for\u00e7a divertit i hem apr\u00e8s moltes coses sobre&hellip;  <a href=\"https:\/\/agora.xtec.cat\/ceippereviver\/i3-i4-i5\/p-4-b-treballem-miro\/\" title=\"Read P-4 B TREBALLEM MIRO\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":10,"featured_media":3571,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[117,2,97,4],"tags":[],"class_list":["post-3579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curs-2018-2019","category-i3-i4-i5","category-nascuts-2014","category-portada"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/3579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/comments?post=3579"}],"version-history":[{"count":1,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/3579\/revisions"}],"predecessor-version":[{"id":3580,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/3579\/revisions\/3580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/media\/3571"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/media?parent=3579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/categories?post=3579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/tags?post=3579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}