{"id":2543,"date":"2018-03-18T12:21:16","date_gmt":"2018-03-18T11:21:16","guid":{"rendered":"http:\/\/agora.xtec.cat\/ceippereviver\/?p=2543"},"modified":"2018-03-18T12:21:58","modified_gmt":"2018-03-18T11:21:58","slug":"hem-visistat-la-fundacio-miro","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/ceippereviver\/general\/hem-visistat-la-fundacio-miro\/","title":{"rendered":"HEM VISISTAT LA FUNDACI\u00d3 MIR\u00d3"},"content":{"rendered":"<p>Els nens i les nenes de la classe dels ping\u00fcins hem anat a la Fundaci\u00ed Mir\u00f3. All\u00e0 hem vist en directe les obres que haviem treballat a l&#8217;aula. Hem descobert que s\u00f3n molt m\u00e9s grans del que pens\u00e0vem. Hem descobert que totes les seves obres, fins i tot les escultures, estaven signades amb el seu nom. Ens ho hem passat d&#8217;all\u00f2 m\u00e9s b\u00e9!<\/p>\n<p><a href=\"https:\/\/photos.app.goo.gl\/wph6LjaysPH9BkIE3\" target=\"_blank\" rel=\"noopener noreferrer\">\u00c0lbum<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Els nens i les nenes de la classe dels ping\u00fcins hem anat a la Fundaci\u00ed Mir\u00f3. All\u00e0 hem vist en directe les obres que haviem treballat a l&#8217;aula. Hem descobert que s\u00f3n molt m\u00e9s grans del que pens\u00e0vem. Hem descobert que totes les seves obres,&hellip;  <a href=\"https:\/\/agora.xtec.cat\/ceippereviver\/general\/hem-visistat-la-fundacio-miro\/\" title=\"Read HEM VISISTAT LA FUNDACI\u00d3 MIR\u00d3\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":6,"featured_media":2546,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[96,1,63,4],"tags":[],"class_list":["post-2543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curs-2017-2018","category-general","category-nascuts-2013","category-portada"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/2543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/comments?post=2543"}],"version-history":[{"count":2,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/2543\/revisions"}],"predecessor-version":[{"id":2547,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts\/2543\/revisions\/2547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/media\/2546"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/media?parent=2543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/categories?post=2543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/tags?post=2543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}