{"id":62,"count":147,"description":"","link":"https:\/\/agora.xtec.cat\/ceippereviver\/categoria\/nascuts-2012\/","name":"Nascuts 2012","slug":"nascuts-2012","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/categories\/62","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts?categories=62"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}