{"id":57,"count":49,"description":"","link":"https:\/\/agora.xtec.cat\/ceippereviver\/categoria\/nascuts-2006\/","name":"Nascuts 2006","slug":"nascuts-2006","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/categories\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/agora.xtec.cat\/ceippereviver\/wp-json\/wp\/v2\/posts?categories=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}